{"id":39064,"date":"2025-06-03T14:28:43","date_gmt":"2025-06-03T12:28:43","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?post_type=tagung&#038;p=39064"},"modified":"2025-06-05T12:51:40","modified_gmt":"2025-06-05T10:51:40","slug":"netzelektrikertag","status":"publish","type":"tagung","link":"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/","title":{"rendered":"Netzelektrikertag 2026"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Gemeinsam mit dem Netzelektrikerforum pr\u00e4sentieren wir Ihnen eine Tagung mit handfestem Praxisbezug. Neue und bew\u00e4hrte Installationstechniken, die elektrische Sicherheit und normative Themen stehen im Fokus der Veranstaltung. Freuen Sie sich auf spannende Referate von versierten Fachexperten der Netzelektriker-Branche. Tauschen Sie sich mit Ihren Fachkollegen aus und lassen Sie den Tag beim gem\u00fctlichen Feierabendbier ausklingen.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3>Programm<\/h3>\n<p>Das Programm ist noch in Bearbeitung und wird in K\u00fcrze folgen. Wir danken f\u00fcr Ihre Geduld![\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3>Zielgruppe<\/h3>\n<p>Der Netzelektrikertag richtet sich an Netzelektriker*innen, Netzfachleute und Netzelektrikermeister*innen.[\/vc_column_text]<div class=\"wpb_contact_column wpb_content_element wpb_contact_column--container\"><div class=\"wpb_wrapper\"><div class=\"contact_container_outer\"><div class=\"contact_container\"><div class=\"contact row middle-xs\"><div class=\"contact__img col-sm-5 col-xs-12\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/06\/Simon-Sonderegger_320x320.png\" alt=\"Simon Sonderegger - Projektleiter Verteilnetze\" \/><\/div><div class=\"contact__info col-sm-7 col-xs-12\"><p><b>Simon Sonderegger<\/b><br>Projektleiter Verteilnetze<\/p><div class=\"phone has-link\"><a href=\"tel:+41585951538\">+41 58 595 15 38<\/a><\/div><div class=\"mail has-link\"><a href=\"mailto:&#115;&#x69;&#x6d;&#111;&#x6e;&#x2e;&#115;&#x6f;&#x6e;&#100;&#x65;&#x72;&#101;&#x67;&#x67;&#101;&#x72;&#x40;&#101;&#x6c;&#x65;&#99;&#x74;&#x72;&#111;&#x73;&#x75;i&#x73;&#x73;e&#x2e;&#x63;h\">simon.sonderegger@<br>electrosuisse.ch<\/a><\/div><\/div><\/div><\/div><\/div><div class=\"contact_container_outer\"><div class=\"contact_container\"><div class=\"contact row middle-xs\"><div class=\"contact__img col-sm-5 col-xs-12\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2020\/07\/BainNathalie-1.jpg\" alt=\"Nathalie Bain - Administration\" \/><\/div><div class=\"contact__info col-sm-7 col-xs-12\"><p><b>Nathalie Bain<\/b><br>Administration<\/p><div class=\"phone has-link\"><a href=\"tel:+41585951511\">+41 58 595 15 11<\/a><\/div><div class=\"mail has-link\"><a href=\"mailto:&#x74;&#97;g&#x75;&#110;g&#x65;&#110;&#64;&#x65;&#x6c;&#101;&#x63;&#x74;&#114;o&#x73;&#117;i&#x73;&#115;e&#x2e;&#x63;&#104;\">&#x74;&#97;g&#x75;&#110;g&#x65;&#110;&#64;&#x65;&#x6c;&#101;&#x63;&#x74;&#114;o&#x73;&#117;i&#x73;&#115;e&#x2e;&#x63;&#104;<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"template":"","class_list":["post-39064","tagung","type-tagung","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netzelektriker: Fachwissen und Netzwerk aufbauen - Electrosuisse<\/title>\n<meta name=\"description\" content=\"Informieren Sie sich \u00fcber neueste Trends auf dem Netzelektrikertag. Spannende Themen und Fachexperten erwarten Sie.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netzelektriker: Fachwissen und Netzwerk aufbauen - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"Informieren Sie sich \u00fcber neueste Trends auf dem Netzelektrikertag. Spannende Themen und Fachexperten erwarten Sie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T10:51:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/06\/netzelektriker_2_1660x470.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1578\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/\",\"name\":\"Netzelektriker: Fachwissen und Netzwerk aufbauen - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\"},\"datePublished\":\"2025-06-03T12:28:43+00:00\",\"dateModified\":\"2025-06-05T10:51:40+00:00\",\"description\":\"Informieren Sie sich \u00fcber neueste Trends auf dem Netzelektrikertag. Spannende Themen und Fachexperten erwarten Sie.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Netzelektriker: Fachwissen und Netzwerk aufbauen - Electrosuisse","description":"Informieren Sie sich \u00fcber neueste Trends auf dem Netzelektrikertag. Spannende Themen und Fachexperten erwarten Sie.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Netzelektriker: Fachwissen und Netzwerk aufbauen - Electrosuisse","og_description":"Informieren Sie sich \u00fcber neueste Trends auf dem Netzelektrikertag. Spannende Themen und Fachexperten erwarten Sie.","og_url":"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/","og_site_name":"Electrosuisse","article_modified_time":"2025-06-05T10:51:40+00:00","og_image":[{"width":1578,"height":650,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/06\/netzelektriker_2_1660x470.png","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/","url":"https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/","name":"Netzelektriker: Fachwissen und Netzwerk aufbauen - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website"},"datePublished":"2025-06-03T12:28:43+00:00","dateModified":"2025-06-05T10:51:40+00:00","description":"Informieren Sie sich \u00fcber neueste Trends auf dem Netzelektrikertag. Spannende Themen und Fachexperten erwarten Sie.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/it\/tagung\/netzelektrikertag\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tagung\/39064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tagung"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/types\/tagung"}],"version-history":[{"count":5,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tagung\/39064\/revisions"}],"predecessor-version":[{"id":39136,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tagung\/39064\/revisions\/39136"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/media?parent=39064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}