{"id":38889,"date":"2025-04-29T08:57:56","date_gmt":"2025-04-29T06:57:56","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=38889"},"modified":"2025-06-17T11:04:42","modified_gmt":"2025-06-17T09:04:42","slug":"uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/","title":{"rendered":"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Le installazioni conformi alla messa al neutro secondo lo schema III costituiscono un notevole rischio per la sicurezza e da tempo non rappresentano pi\u00f9 lo stato della tecnica. In collaborazione con EIT.swiss e VSEK, Electrosuisse ha realizzato un opuscolo informativo compatto per aiutare il personale del settore elettrico a fornire ai proprietari di case informazioni concrete sulla necessit\u00e0 di un risanamento.<\/p>\n<p>L&#8217;opuscolo fornisce una panoramica pratica dei modelli di guasto tipici e spiega quando \u00e8 richiesto il risanamento dal punto di vista tecnico e giuridico.<\/p>\n<p><strong>Perch\u00e9 la messa al neutro secondo lo schema III \u00e8 problematica?<\/strong><br \/>\nQuesto storico metodo di installazione assegna la funzione di conduttore di protezione al conduttore neutro, precedentemente conduttore a tensione zero. Anche un solo guasto, ad esempio un conduttore neutro interrotto, un cablaggio invertito o un ponticello mancante tra i conduttori N e PE, pu\u00f2 causare la messa in tensione degli involucri. La disinserzione automatica in caso di guasto non \u00e8 sempre garantita. Inoltre, \u00e8 tecnicamente quasi impossibile installare a posteriori gli RCD. Il rischio di scosse elettriche, incendi e danni alle cose \u00e8 notevole.<\/p>\n<p><strong>Contesto legale<\/strong><br \/>\nIl proprietario dell&#8217;impianto \u00e8 responsabile della sicurezza dell&#8217;impianto elettrico. Secondo l&#8217;Ordinanza sugli impianti a bassa tensione (OIBT, RS 734.27) e l&#8217;Ordinanza sulle correnti forti (RS 734.2), le installazioni elettriche devono essere conformi alle regole riconosciute della tecnica e non devono costituire un pericolo. Se le installazioni conformi alla messa al neutro secondo lo schema III non soddisfano pi\u00f9 questi requisiti a causa dell&#8217;invecchiamento e della manipolazione, non \u00e8 pi\u00f9 garantita alcuna protezione per gli impianti esistenti. Inoltre, nel 2018 l&#8217;intervallo di ispezione degli impianti interessati \u00e8 stato ridotto a cinque anni, aumentando ulteriormente l&#8217;obbligo di intervento. In molti casi non vengono pi\u00f9 rilasciati i rapporti di sicurezza. La direttiva ESTI n. 225 specifica i requisiti legali e chiarisce che: il risanamento delle installazioni con messa al neutro secondo lo schema III \u00e8 imprescindibile.<\/p>\n<p><strong>Download<\/strong><br \/>\nL&#8217;opuscolo \u00e8 gi\u00e0 disponibile in <a href=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Flyer_neutro-secondo-lo-schema-III.pdf\"><strong><em>formato<\/em><\/strong><\/a> digitale<\/p>\n<p><strong>Ordinazione di copie cartacee:<\/strong><br \/>\nIl pieghevole pu\u00f2 essere richiesto tramite e-mail all&#8217;indirizzo <a href=\"&#x6d;&#97;&#105;l&#x74;&#x6f;&#58;w&#x65;&#x69;&#116;e&#x72;&#x62;&#105;l&#x64;&#x75;&#110;g&#x40;&#x65;&#108;e&#x63;&#x74;&#114;&#111;s&#x75;&#x69;&#115;s&#x65;&#x2e;&#99;h\">&#119;&#x65;&#105;&#x74;&#101;&#x72;&#98;&#x69;&#108;&#x64;&#117;&#x6e;&#103;&#x40;&#101;&#x6c;&#101;&#x63;&#116;&#x72;&#111;&#x73;&#117;&#x69;&#115;&#x73;&#101;&#x2e;&#99;&#x68;<\/a>.<\/p>\n<p>La quantit\u00e0 massima ordinabile per ogni cliente \u00e8 di 50 copie.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Le installazioni conformi alla messa al neutro secondo lo schema III costituiscono un notevole rischio per la sicurezza e da tempo non rappresentano pi\u00f9 lo stato della tecnica. In collaborazione con EIT.swiss e VSEK, Electrosuisse ha realizzato un opuscolo informativo compatto per aiutare il personale del settore elettrico a fornire ai proprietari di case [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[45],"tags":[245,265,249,253],"class_list":["post-38889","post","type-post","status-publish","format-standard","hentry","category-non-categorizzato","tag-energia-e-reti","tag-energieversorgung-it","tag-ingegneria-degli-edifici","tag-produktion-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Le installazioni conformi alla messa al neutro secondo lo schema III costituiscono un notevole rischio per la sicurezza e da tempo non rappresentano pi\u00f9 lo stato della tecnica. In collaborazione con EIT.swiss e VSEK, Electrosuisse ha realizzato un opuscolo informativo compatto per aiutare il personale del settore elettrico a fornire ai proprietari di case [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-29T06:57:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T09:04:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/electrosuisse-logo-1200x675-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Shea Heller\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/\"},\"author\":{\"name\":\"Shea Heller\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/99ddccc3c3a651c967aef30f8dbbd750\"},\"headline\":\"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III\",\"datePublished\":\"2025-04-29T06:57:56+00:00\",\"dateModified\":\"2025-06-17T09:04:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/\"},\"wordCount\":375,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"keywords\":[\"Elektroinstallation IT\",\"Energieversorgung IT\",\"Geb\u00e4udetechnik IT\",\"Produktion und Dienstleistung IT\"],\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/\",\"name\":\"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\"},\"datePublished\":\"2025-04-29T06:57:56+00:00\",\"dateModified\":\"2025-06-17T09:04:42+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/99ddccc3c3a651c967aef30f8dbbd750\",\"name\":\"Shea Heller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c63739e3c3ba45ac72bd92f466dcb182677e111ccac99e05e4d4b34621412d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c63739e3c3ba45ac72bd92f466dcb182677e111ccac99e05e4d4b34621412d9?s=96&d=mm&r=g\",\"caption\":\"Shea Heller\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Le installazioni conformi alla messa al neutro secondo lo schema III costituiscono un notevole rischio per la sicurezza e da tempo non rappresentano pi\u00f9 lo stato della tecnica. In collaborazione con EIT.swiss e VSEK, Electrosuisse ha realizzato un opuscolo informativo compatto per aiutare il personale del settore elettrico a fornire ai proprietari di case [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/","og_site_name":"Electrosuisse","article_published_time":"2025-04-29T06:57:56+00:00","article_modified_time":"2025-06-17T09:04:42+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/electrosuisse-logo-1200x675-1.png","type":"image\/png"}],"author":"Shea Heller","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/"},"author":{"name":"Shea Heller","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/99ddccc3c3a651c967aef30f8dbbd750"},"headline":"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III","datePublished":"2025-04-29T06:57:56+00:00","dateModified":"2025-06-17T09:04:42+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/"},"wordCount":375,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"keywords":["Elektroinstallation IT","Energieversorgung IT","Geb\u00e4udetechnik IT","Produktion und Dienstleistung IT"],"articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/","url":"https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/","name":"Un\u2019eredit\u00e0 perocolosa: nuovo opuscolo per il risanamento della messa al neutro secondo lo schema III - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website"},"datePublished":"2025-04-29T06:57:56+00:00","dateModified":"2025-06-17T09:04:42+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/it\/uneredita-perocolosa-nuovo-opuscolo-per-il-risanamento-della-messa-al-neutro-secondo-lo-schema-iii\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/99ddccc3c3a651c967aef30f8dbbd750","name":"Shea Heller","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4c63739e3c3ba45ac72bd92f466dcb182677e111ccac99e05e4d4b34621412d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c63739e3c3ba45ac72bd92f466dcb182677e111ccac99e05e4d4b34621412d9?s=96&d=mm&r=g","caption":"Shea Heller"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/38889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/comments?post=38889"}],"version-history":[{"count":2,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/38889\/revisions"}],"predecessor-version":[{"id":39240,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/38889\/revisions\/39240"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/media?parent=38889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/categories?post=38889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tags?post=38889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}