{"id":30053,"date":"2023-04-06T10:00:16","date_gmt":"2023-04-06T08:00:16","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=30053"},"modified":"2023-04-11T14:10:58","modified_gmt":"2023-04-11T12:10:58","slug":"piu-sostenibilita-nellelettromobilita","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/","title":{"rendered":"Pi\u00f9 sostenibilit\u00e0 nell&#8217;elettromobilit\u00e0"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>Per determinare le condizioni delle celle della batteria in modo pi\u00f9 preciso ed evitare onerose prove di laboratorio, presso il Fraunhofer IFAM di Brema \u00e8 stato ulteriormente sviluppato il metodo per determinare la resistenza della corrente alternata all&#8217;interno della batteria utilizzando la spettroscopia di impedenza dinamica. In questo modo \u00e8 possibile effettuare misurazioni durante il funzionamento, che consentono di trarre informazioni sulle prestazioni in tempo reale.<\/strong><\/p>\n<p>Molti sono i fattori determinanti l&#8217;invecchiamento delle celle delle batterie. Oltre all&#8217;invecchiamento solare, determinato principalmente dalle temperature di stoccaggio e dallo stato di carica durante l&#8217;immagazzinamento, \u00e8 decisiva la storia di tutti i processi di carica e scarica con i carichi e le temperature che si sono verificati in ciascun caso. I fattori di influenza sono quindi numerosi e variabili per lunghi periodi di tempo, motivo per cui la determinazione precisa dello stato di invecchiamento \u00e8 complessa ed \u00e8 risultata finora molto onerosa. Gli approcci esistenti si basano o su simulazioni che rappresentano una descrizione semplificata del sistema di batterie e del processo di decomposizione, o su estrapolazioni sperimentali della durata del ciclo delle celle della batteria. In questo caso, viene determinata la relazione empirica tra l&#8217;impedenza misurata di una cella e la capacit\u00e0 della batteria.<\/p>\n<p>Per la modellazione simulativa, \u00e8 necessario conoscere i processi dettagliati per ogni tipo di cella. Inoltre, l&#8217;intero processo di descrizione va ripetuto per il trasferimento a una nuova chimica di cella, il che richiede molto tempo. Ci\u00f2 vale anche per l&#8217;estrapolazione dalle misure, poich\u00e9 in questo caso \u00e8 necessario eseguire l&#8217;intero lavoro di misurazione per ogni tipo di cella da descrivere e per tutte le condizioni ambientali esistenti (temperatura, profilo di carico, ecc.).<\/p>\n<p>Con il nuovo approccio di sviluppo per determinare la durata di vita, il sistema di batterie viene dotato di una memoria di tutti i processi. Nel nuovo approccio, la vita utile delle celle della batteria viene descritta utilizzando un modello basato su una conoscenza limitata della chimica delle celle. A tal fine, per descrivere le propriet\u00e0 delle celle si utilizzano modelli matematici di comportamento non lineare con &#8220;effetti di memoria&#8221; (la cosiddetta serie di Volterra). Questo approccio ha il vantaggio che in qualsiasi momento l&#8217;output del sistema dipende dall&#8217;input dello stesso, quindi il sistema conserva una memoria di tutti i processi precedenti, essenziale per descrivere il processo di invecchiamento.<\/p>\n<p>Il passo cruciale \u00e8 quindi quello di misurare l&#8217;impedenza dinamica delle celle della batteria durante l&#8217;uso, cio\u00e8 durante la carica o la scarica della cella. \u00c8 possibile misurare direttamente i parametri matematici che descrivono il comportamento delle celle. Con l&#8217;aiuto di questa rappresentazione matematica, \u00e8 possibile prendere in considerazione anche gli stati non ancora misurati, consentendo la trasferibilit\u00e0 ad altre condizioni ambientali e chimiche delle celle, ovvero ipotizzare la creazione di nuovi tipi di batterie.<\/p>\n<p>Il nuovo metodo offre non solo la possibilit\u00e0 di trasferire con poco sforzo i risultati a tipi di celle completamente diversi (ad esempio, batterie allo stato solido), ma soprattutto il vantaggio che le misurazioni possono essere effettuate direttamente durante l&#8217;uso di una batteria, ad esempio in un&#8217;auto elettrica. Non sono necessari ulteriori prove di laboratorio o limitazioni d&#8217;uso per la determinazione dell&#8217;et\u00e0.<\/p>\n<p>Grazie all&#8217;implementazione nel sistema di gestione della batteria, \u00e8 possibile ottenere tutti i dati necessari per la previsione della vita utile mentre il sistema \u00e8 in uso. Inoltre, sulla base di questi dati \u00e8 possibile sviluppare strategie di carica ottimizzate per aumentare la durata complessiva del sistema di batterie. In questo modo si riducono i costi di vita e si aumenta la sostenibilit\u00e0 dell&#8217;utilizzo di un sistema di batterie nell&#8217;applicazione.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Per determinare le condizioni delle celle della batteria in modo pi\u00f9 preciso ed evitare onerose prove di laboratorio, presso il Fraunhofer IFAM di Brema \u00e8 stato ulteriormente sviluppato il metodo per determinare la resistenza della corrente alternata all&#8217;interno della batteria utilizzando la spettroscopia di impedenza dinamica. In questo modo \u00e8 possibile effettuare misurazioni durante il [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[45],"tags":[370,251,253],"class_list":["post-30053","post","type-post","status-publish","format-standard","hentry","category-non-categorizzato","tag-mobilitaet-it","tag-mobilita-e-infrastrutture","tag-produktion-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pi\u00f9 sostenibilit\u00e0 nell&#039;elettromobilit\u00e0 - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi\u00f9 sostenibilit\u00e0 nell&#039;elettromobilit\u00e0 - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Per determinare le condizioni delle celle della batteria in modo pi\u00f9 preciso ed evitare onerose prove di laboratorio, presso il Fraunhofer IFAM di Brema \u00e8 stato ulteriormente sviluppato il metodo per determinare la resistenza della corrente alternata all&#8217;interno della batteria utilizzando la spettroscopia di impedenza dinamica. In questo modo \u00e8 possibile effettuare misurazioni durante il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T08:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T12:10:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/04\/Nachhaltigkeit-Elektromobilitaet_1660x470.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nalini Schempp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/\"},\"author\":{\"name\":\"Nalini Schempp\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\"},\"headline\":\"Pi\u00f9 sostenibilit\u00e0 nell&#8217;elettromobilit\u00e0\",\"datePublished\":\"2023-04-06T08:00:16+00:00\",\"dateModified\":\"2023-04-11T12:10:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/\"},\"wordCount\":616,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"keywords\":[\"Mobilit\u00e4t\",\"Mobilit\u00e4t IT\",\"Produktion und Dienstleistung IT\"],\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/\",\"name\":\"Pi\u00f9 sostenibilit\u00e0 nell'elettromobilit\u00e0 - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\"},\"datePublished\":\"2023-04-06T08:00:16+00:00\",\"dateModified\":\"2023-04-11T12:10:58+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\",\"name\":\"Nalini Schempp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"caption\":\"Nalini Schempp\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pi\u00f9 sostenibilit\u00e0 nell'elettromobilit\u00e0 - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Pi\u00f9 sostenibilit\u00e0 nell'elettromobilit\u00e0 - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text]Per determinare le condizioni delle celle della batteria in modo pi\u00f9 preciso ed evitare onerose prove di laboratorio, presso il Fraunhofer IFAM di Brema \u00e8 stato ulteriormente sviluppato il metodo per determinare la resistenza della corrente alternata all&#8217;interno della batteria utilizzando la spettroscopia di impedenza dinamica. In questo modo \u00e8 possibile effettuare misurazioni durante il [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/","og_site_name":"Electrosuisse","article_published_time":"2023-04-06T08:00:16+00:00","article_modified_time":"2023-04-11T12:10:58+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/04\/Nachhaltigkeit-Elektromobilitaet_1660x470.jpg","type":"image\/png"}],"author":"Nalini Schempp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/"},"author":{"name":"Nalini Schempp","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08"},"headline":"Pi\u00f9 sostenibilit\u00e0 nell&#8217;elettromobilit\u00e0","datePublished":"2023-04-06T08:00:16+00:00","dateModified":"2023-04-11T12:10:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/"},"wordCount":616,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"keywords":["Mobilit\u00e4t","Mobilit\u00e4t IT","Produktion und Dienstleistung IT"],"articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/","url":"https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/","name":"Pi\u00f9 sostenibilit\u00e0 nell'elettromobilit\u00e0 - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website"},"datePublished":"2023-04-06T08:00:16+00:00","dateModified":"2023-04-11T12:10:58+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/it\/piu-sostenibilita-nellelettromobilita\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08","name":"Nalini Schempp","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","caption":"Nalini Schempp"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/30053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/comments?post=30053"}],"version-history":[{"count":1,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/30053\/revisions"}],"predecessor-version":[{"id":30054,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/30053\/revisions\/30054"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/media?parent=30053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/categories?post=30053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tags?post=30053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}