{"id":25446,"date":"2021-09-28T10:00:28","date_gmt":"2021-09-28T08:00:28","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=25446"},"modified":"2022-12-14T13:12:37","modified_gmt":"2022-12-14T12:12:37","slug":"nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/","title":{"rendered":"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>Nel 2020, circa il 76% (2019: 75%) dell&#8217;elettricit\u00e0 prodotta dalle prese svizzere proveniva da energie rinnovabili: il 66% da grandi centrali idroelettriche e circa il 10,3% da fotovoltaico, eolico, piccole centrali idroelettriche e biomassa. Il 20% \u00e8 stato prodotto con l\u2019energia nucleare e poco meno del 2% con rifiuti e fonti di energia fossile. L&#8217;origine e la composizione del 2% dell&#8217;elettricit\u00e0 fornita non possono essere verificate (2019: 4%).<\/strong><\/p>\n<p>I dati sul mix di fornitura di energia elettrica in Svizzera (mix di energia elettrica che esce dalla presa, vedi riquadro) vengono raccolti annualmente e pubblicati sul sito www.strom.ch\/it\/service\/etichettatura-elettricita nel cockpit di etichettatura dell&#8217;energia elettrica. I dati pubblicati di recente forniscono informazioni sulle forniture di energia elettrica nel 2020. La dichiarazione completa di energia per l&#8217;etichettatura dell&#8217;energia elettrica \u00e8 divenuta obbligatoria nel 2018. Ci\u00f2 significa che l&#8217;elettricit\u00e0 di origine sconosciuta, la cosiddetta elettricit\u00e0 grigia, \u00e8 consentita solo in casi eccezionali e fino al 2020. Poich\u00e9 la maggior parte dei Paesi limitrofi non rilascia garanzie di origine per l&#8217;elettricit\u00e0 prodotta da centrali elettriche convenzionali, la Svizzera ha introdotto le cosiddette garanzie sostitutive. Ci\u00f2 significa che l&#8217;elettricit\u00e0 a carbone proveniente dall&#8217;estero pu\u00f2 essere dichiarata come tale e non \u00e8 pi\u00f9 classificata come \u00ab grigia \u00bb. La quota di elettricit\u00e0 da carbone importata con tali certificati sostitutivi si \u00e8 ulteriormente dimezzata tra il 2019 e il 2020, passando allo 0,25%.<\/p>\n<ul>\n<li>Il 66% dell&#8217;elettricit\u00e0 fornita nel 2020 \u00e8 stato prodotto da <strong>grandi centrali idroelettriche<\/strong> (come l\u2019anno precedente). Il 76% dell&#8217;energia idroelettrica fornita \u00e8 stata prodotta in Svizzera (2019: 73,7%).<\/li>\n<li>Il 19,9% (2019: 19,1%) dell&#8217;elettricit\u00e0 fornita \u00e8 stata prodotta in <strong>centrali nucleari<\/strong>. Questo dato \u00e8 inferiore alla quota di energia nucleare nel mix di produzione svizzero (32,9%). Come nell&#8217;anno precedente, l&#8217;energia nucleare fornita proviene quasi esclusivamente dalla Svizzera.<\/li>\n<li>Il 2,1% (2019: 4,3%) dell&#8217;elettricit\u00e0 fornita proviene da <strong>fonti energetiche non verificabili<\/strong>. Con l&#8217;introduzione della dichiarazione completa nel gennaio 2018, le fonti energetiche non verificabili non sono pi\u00f9 consentite, ad eccezione dei contratti di fornitura pluriennali stipulati prima del 1\u00b0 novembre 2017 (per i quali si applica un periodo transitorio fino all&#8217;anno di fornitura 2020). Come previsto, la quota di fonti energetiche non verificabili \u00e8 diminuita grazie alla dichiarazione completa. Le aziende ad alta intensit\u00e0 di energia elettrica acquistano i cosiddetti certificati sostitutivi per l&#8217;elettricit\u00e0 da fonti fossili e nucleari da centrali europee per le quali non vengono rilasciate regolari garanzie di origine.<\/li>\n<li>La quota di nuove fonti di energia rinnovabile (solare, eolica, biomassa e piccole centrali idroelettriche) \u00e8 continuata ad aumentare, passando dall&#8217;8,4% (2019) al 10,3% nel 2020. Circa l&#8217;87% \u00e8 stato prodotto in Svizzera e ben due terzi sono stati sovvenzionati dal Sistema di rimunerazione per l\u2019immissione di elettricit\u00e0 (SRI).<\/li>\n<li>In piccole quantit\u00e0, l&#8217;elettricit\u00e0 fornita nel 2020 proveniva da <strong>fonti energetiche fossili<\/strong> (1,8%, anno precedente 2%).<\/li>\n<\/ul>\n<h3><strong><br \/>\n<\/strong>Il mix di produzione non coincide con il mix di fornitura<\/h3>\n<p>In Svizzera, il 58,1% dell&#8217;elettricit\u00e0 viene prodotto da centrali idroelettriche, il 32,9% da centrali nucleari, il 2,3% da combustibili fossili e poco meno del 6,7% da nuove energie rinnovabili (= mix di produzione svizzero 2020). Tuttavia, non \u00e8 solo l&#8217;elettricit\u00e0 di produzione svizzera a essere fornita alle prese di corrente nazionali: gli scambi commerciali con l&#8217;estero sono intensi e l&#8217;elettricit\u00e0 viene esportata e importata. Pertanto, il mix di produzione svizzero non corrisponde alla composizione media dell&#8217;elettricit\u00e0 fornita (= mix di fornitura svizzero).<\/p>\n<p>Per aver un quadro\u00a0 trasparente del mix fornito da ciascun fornitore di energia elettrica e consentire cos\u00ec ai consumatori di prendere una decisione informata a favore di un determinato prodotto elettrico, dal 2005 le societ\u00e0 svizzere di fornitura di energia elettrica sono obbligate per legge a rendere nota l&#8217;origine e la composizione dell&#8217;energia elettrica fornita. La dichiarazione si basa sempre sui dati dell&#8217;anno solare precedente. Dal 2006, questi dati devono essere comunicati a tutti i clienti con la bolletta dell&#8217;elettricit\u00e0. Dal 2013 i dati sono pubblicati anche sulla piattaforma internet <a href=\"https:\/\/www.strom.ch\/it\/service\/etichettatura-elettricita\" target=\"_blank\" rel=\"noopener\">www.strom.ch\/it\/service\/etichettatura-elettricita<\/a>.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Nel 2020, circa il 76% (2019: 75%) dell&#8217;elettricit\u00e0 prodotta dalle prese svizzere proveniva da energie rinnovabili: il 66% da grandi centrali idroelettriche e circa il 10,3% da fotovoltaico, eolico, piccole centrali idroelettriche e biomassa. Il 20% \u00e8 stato prodotto con l\u2019energia nucleare e poco meno del 2% con rifiuti e fonti di energia fossile. L&#8217;origine [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[45],"tags":[265],"class_list":["post-25446","post","type-post","status-publish","format-standard","hentry","category-non-categorizzato","tag-energieversorgung-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Nel 2020, circa il 76% (2019: 75%) dell&#8217;elettricit\u00e0 prodotta dalle prese svizzere proveniva da energie rinnovabili: il 66% da grandi centrali idroelettriche e circa il 10,3% da fotovoltaico, eolico, piccole centrali idroelettriche e biomassa. Il 20% \u00e8 stato prodotto con l\u2019energia nucleare e poco meno del 2% con rifiuti e fonti di energia fossile. L&#8217;origine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-28T08:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T12:12:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/11\/Schweizer-Steckdosen_1660x470.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nalini Schempp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/\"},\"author\":{\"name\":\"Nalini Schempp\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\"},\"headline\":\"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile\",\"datePublished\":\"2021-09-28T08:00:28+00:00\",\"dateModified\":\"2022-12-14T12:12:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/\"},\"wordCount\":645,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"keywords\":[\"Energieversorgung IT\"],\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/\",\"name\":\"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\"},\"datePublished\":\"2021-09-28T08:00:28+00:00\",\"dateModified\":\"2022-12-14T12:12:37+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\",\"name\":\"Nalini Schempp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"caption\":\"Nalini Schempp\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text]Nel 2020, circa il 76% (2019: 75%) dell&#8217;elettricit\u00e0 prodotta dalle prese svizzere proveniva da energie rinnovabili: il 66% da grandi centrali idroelettriche e circa il 10,3% da fotovoltaico, eolico, piccole centrali idroelettriche e biomassa. Il 20% \u00e8 stato prodotto con l\u2019energia nucleare e poco meno del 2% con rifiuti e fonti di energia fossile. L&#8217;origine [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/","og_site_name":"Electrosuisse","article_published_time":"2021-09-28T08:00:28+00:00","article_modified_time":"2022-12-14T12:12:37+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/11\/Schweizer-Steckdosen_1660x470.jpg","type":"image\/png"}],"author":"Nalini Schempp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/"},"author":{"name":"Nalini Schempp","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08"},"headline":"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile","datePublished":"2021-09-28T08:00:28+00:00","dateModified":"2022-12-14T12:12:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/"},"wordCount":645,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"keywords":["Energieversorgung IT"],"articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/","url":"https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/","name":"Nel 2020 le prese svizzere hanno fornito il 76% di elettricit\u00e0 rinnovabile - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website"},"datePublished":"2021-09-28T08:00:28+00:00","dateModified":"2022-12-14T12:12:37+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/it\/nel-2020-le-prese-svizzere-hanno-fornito-il-76-di-elettricita-rinnovabile\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08","name":"Nalini Schempp","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","caption":"Nalini Schempp"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/25446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/comments?post=25446"}],"version-history":[{"count":0,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/25446\/revisions"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/media?parent=25446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/categories?post=25446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tags?post=25446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}