{"id":25434,"date":"2022-05-19T10:00:10","date_gmt":"2022-05-19T08:00:10","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=25434"},"modified":"2022-12-14T12:52:35","modified_gmt":"2022-12-14T11:52:35","slug":"la-roadmap-dellelettromobilita-prolungata-fino-al-2025","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/","title":{"rendered":"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>La roadmap dell\u2019elettromobilit\u00e0 sta entrando in una nuova fase. Alti rappresentanti dei settori automobilistico, elettrico immobiliare e delle flotte di veicoli, nonch\u00e9 la Confederazione, i cantoni, le citt\u00e0 e i comuni hanno esteso la tabella di marcia al 2025. Per la nuova fase sono stati definiti tre nuovi obiettivi.<\/strong><\/p>\n<p>Entro la fine del 2025, la quota di veicoli plug-in (auto elettriche pure e ibride plug-in) tra le nuove immatricolazioni dovrebbe raggiungere il 50%. Nel primo trimestre del 2022, tale quota aveva gi\u00e0 raggiunto il 25,5%. Entro la fine del 2025 dovrebbero essere disponibili 20.000 stazioni di ricarica pubbliche. All&#8217;inizio del 2022, in Svizzera se ne contavano circa 7150. Infine, \u00e8 stato definito anche l&#8217;obiettivo qualitativo \u00abRicarica a misura di utente e al servizio della rete a domicilio, presso la sede di lavoro e in viaggio\u00bb. Per raggiungere questi tre obiettivi, gli attori della roadmap si impegnano ad adottare misure volontarie nei propri rispettivi campi d&#8217;azione.<\/p>\n<p>La richiesta di nuove misure ha avuto una risposta attiva. 59 organizzazioni stanno dando forma alla roadmap 2025 con 75 misure, di cui 44 nuove e 31 adattate o ampliate. Uno dei cardini di questa nuova tappa sono le misure comuni tra gli attori per affrontare sfide particolarmente rilevanti: la ricarica negli edifici con pi\u00f9 unit\u00e0 abitative, la ricarica nel quartiere e l\u2019economia circolare delle batterie di trazione (riutilizzo come batterie di seconda vita e riciclaggio).<\/p>\n<p>La roadmap dell\u2019elettromobilit\u00e0 \u00e8 aperta anche ad altre organizzazioni e aziende che vogliano contribuire al raggiungimento degli obiettivi.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]La roadmap dell\u2019elettromobilit\u00e0 sta entrando in una nuova fase. Alti rappresentanti dei settori automobilistico, elettrico immobiliare e delle flotte di veicoli, nonch\u00e9 la Confederazione, i cantoni, le citt\u00e0 e i comuni hanno esteso la tabella di marcia al 2025. Per la nuova fase sono stati definiti tre nuovi obiettivi. Entro la fine del 2025, la [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[45],"tags":[251],"class_list":["post-25434","post","type-post","status-publish","format-standard","hentry","category-non-categorizzato","tag-mobilita-e-infrastrutture"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025 - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025 - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]La roadmap dell\u2019elettromobilit\u00e0 sta entrando in una nuova fase. Alti rappresentanti dei settori automobilistico, elettrico immobiliare e delle flotte di veicoli, nonch\u00e9 la Confederazione, i cantoni, le citt\u00e0 e i comuni hanno esteso la tabella di marcia al 2025. Per la nuova fase sono stati definiti tre nuovi obiettivi. Entro la fine del 2025, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-19T08:00:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T11:52:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/05\/Roadmap-Elektromobilitaet_1660x470.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nalini Schempp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/\"},\"author\":{\"name\":\"Nalini Schempp\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\"},\"headline\":\"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025\",\"datePublished\":\"2022-05-19T08:00:10+00:00\",\"dateModified\":\"2022-12-14T11:52:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/\"},\"wordCount\":260,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"keywords\":[\"Mobilit\u00e4t IT\"],\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/\",\"name\":\"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025 - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\"},\"datePublished\":\"2022-05-19T08:00:10+00:00\",\"dateModified\":\"2022-12-14T11:52:35+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\",\"name\":\"Nalini Schempp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"caption\":\"Nalini Schempp\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025 - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025 - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text]La roadmap dell\u2019elettromobilit\u00e0 sta entrando in una nuova fase. Alti rappresentanti dei settori automobilistico, elettrico immobiliare e delle flotte di veicoli, nonch\u00e9 la Confederazione, i cantoni, le citt\u00e0 e i comuni hanno esteso la tabella di marcia al 2025. Per la nuova fase sono stati definiti tre nuovi obiettivi. Entro la fine del 2025, la [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/","og_site_name":"Electrosuisse","article_published_time":"2022-05-19T08:00:10+00:00","article_modified_time":"2022-12-14T11:52:35+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/05\/Roadmap-Elektromobilitaet_1660x470.jpg","type":"image\/png"}],"author":"Nalini Schempp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/"},"author":{"name":"Nalini Schempp","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08"},"headline":"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025","datePublished":"2022-05-19T08:00:10+00:00","dateModified":"2022-12-14T11:52:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/"},"wordCount":260,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"keywords":["Mobilit\u00e4t IT"],"articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/","url":"https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/","name":"La roadmap dell\u2019elettromobilit\u00e0 prolungata fino al 2025 - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website"},"datePublished":"2022-05-19T08:00:10+00:00","dateModified":"2022-12-14T11:52:35+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/it\/la-roadmap-dellelettromobilita-prolungata-fino-al-2025\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08","name":"Nalini Schempp","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev-web.electrosuisse.ch\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","caption":"Nalini Schempp"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/25434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/comments?post=25434"}],"version-history":[{"count":0,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/posts\/25434\/revisions"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/media?parent=25434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/categories?post=25434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/it\/wp-json\/wp\/v2\/tags?post=25434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}