{"id":34393,"date":"2024-03-07T09:40:54","date_gmt":"2024-03-07T08:40:54","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=34393"},"modified":"2024-04-15T16:13:48","modified_gmt":"2024-04-15T14:13:48","slug":"focus-salaire-2024-internationalite","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/","title":{"rendered":"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024!<\/strong><\/p>\n<p><strong>Saisissez l&#8217;occasion, remplissez le questionnaire et profitez des r\u00e9sultats\u00a0!<\/strong><\/p>\n<p>Les r\u00e9sultats de l&#8217;enqu\u00eate exclusive sur l\u2019ensemble de la branche seront publi\u00e9s cet automne et seront compl\u00e9t\u00e9s par des articles informatifs consacr\u00e9s au th\u00e8me de l&#8217;internationalit\u00e9. En tant que membre d&#8217;Electrosuisse, vous recevez le Focus Salaire gratuitement.<\/p>\n<p>R\u00e9pondre aux questions prend environ 15 minutes. Vos r\u00e9ponses seront trait\u00e9es de mani\u00e8re anonyme et confidentielle par l&#8217;institut de sondage Demoscope.<\/p>\n<p>Remplissez d\u00e8s \u00e0 pr\u00e9sent le <a href=\"http:\/\/www.demoscope.swiss\/electrosuisse\">questionnaire<\/a> et contribuez ainsi \u00e0 la transparence de la structure salariale dans le secteur suisse de l&#8217;\u00e9lectricit\u00e9 et de l&#8217;\u00e9nergie\u00a0!<\/p>\n<p>Nous vous remercions de votre collaboration.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024! Saisissez l&#8217;occasion, remplissez le questionnaire et profitez des r\u00e9sultats\u00a0! Les r\u00e9sultats de l&#8217;enqu\u00eate exclusive sur l\u2019ensemble de la branche seront publi\u00e9s cet automne et seront compl\u00e9t\u00e9s par des articles informatifs consacr\u00e9s au th\u00e8me de l&#8217;internationalit\u00e9. En tant que membre d&#8217;Electrosuisse, vous recevez le Focus [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[260,371,248,257,252],"class_list":["post-34393","post","type-post","status-publish","format-standard","hentry","category-non-classifie","tag-installation-electrique","tag-energieversorgung-fr","tag-technique-du-batiment","tag-mobilite-infrastructure","tag-efficacite-energetique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb - Electrosuisse<\/title>\n<meta name=\"description\" content=\"Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024 !\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T08:40:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T14:13:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/03\/Lohnradar-1660x470-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andrea Hinterm\u00fcller\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/\"},\"author\":{\"name\":\"Andrea Hinterm\u00fcller\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/4511b20b7baa8bd28a362b20c15b659f\"},\"headline\":\"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb\",\"datePublished\":\"2024-03-07T08:40:54+00:00\",\"dateModified\":\"2024-04-15T14:13:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/\"},\"wordCount\":144,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"keywords\":[\"Elektroinstallation FR\",\"Energieversorgung\",\"Geb\u00e4udetechnik FR\",\"Mobilit\u00e4t FR\",\"Produktion und Dienstleistung FR\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/\",\"name\":\"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\"},\"datePublished\":\"2024-03-07T08:40:54+00:00\",\"dateModified\":\"2024-04-15T14:13:48+00:00\",\"description\":\"Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024 !\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/4511b20b7baa8bd28a362b20c15b659f\",\"name\":\"Andrea Hinterm\u00fcller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/65ca707900a8dbd7105786d9eb76eb2875a966e7545a220ad2b769e589c780e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/65ca707900a8dbd7105786d9eb76eb2875a966e7545a220ad2b769e589c780e5?s=96&d=mm&r=g\",\"caption\":\"Andrea Hinterm\u00fcller\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb - Electrosuisse","description":"Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024 !","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb - Electrosuisse","og_description":"Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024 !","og_url":"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/","og_site_name":"Electrosuisse","article_published_time":"2024-03-07T08:40:54+00:00","article_modified_time":"2024-04-15T14:13:48+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/03\/Lohnradar-1660x470-1.jpg","type":"image\/png"}],"author":"Andrea Hinterm\u00fcller","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/"},"author":{"name":"Andrea Hinterm\u00fcller","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/4511b20b7baa8bd28a362b20c15b659f"},"headline":"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb","datePublished":"2024-03-07T08:40:54+00:00","dateModified":"2024-04-15T14:13:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/"},"wordCount":144,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"keywords":["Elektroinstallation FR","Energieversorgung","Geb\u00e4udetechnik FR","Mobilit\u00e4t FR","Produktion und Dienstleistung FR"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/","name":"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website"},"datePublished":"2024-03-07T08:40:54+00:00","dateModified":"2024-04-15T14:13:48+00:00","description":"Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024 !","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/4511b20b7baa8bd28a362b20c15b659f","name":"Andrea Hinterm\u00fcller","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/65ca707900a8dbd7105786d9eb76eb2875a966e7545a220ad2b769e589c780e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/65ca707900a8dbd7105786d9eb76eb2875a966e7545a220ad2b769e589c780e5?s=96&d=mm&r=g","caption":"Andrea Hinterm\u00fcller"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/34393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/comments?post=34393"}],"version-history":[{"count":2,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/34393\/revisions"}],"predecessor-version":[{"id":35003,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/34393\/revisions\/35003"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/media?parent=34393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/categories?post=34393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/tags?post=34393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}