{"id":30051,"date":"2023-04-06T10:00:53","date_gmt":"2023-04-06T08:00:53","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=30051"},"modified":"2023-04-11T14:00:48","modified_gmt":"2023-04-11T12:00:48","slug":"plus-de-durabilite-dans-lelectromobilite","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/","title":{"rendered":"Plus de durabilit\u00e9 dans l&#8217;\u00e9lectromobilit\u00e9"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>Afin de pouvoir d\u00e9terminer l&#8217;\u00e9tat des cellules de batterie de mani\u00e8re plus pr\u00e9cise et sans devoir recourir \u00e0 un laboratoire, le Fraunhofer IFAM de Br\u00eame a perfectionn\u00e9 la d\u00e9termination de la r\u00e9sistance du courant alternatif au sein de la batterie au moyen de la spectroscopie d&#8217;imp\u00e9dance dynamique. Il est ainsi possible d&#8217;effectuer des mesures pendant le fonctionnement, ce qui permet d&#8217;obtenir des informations sur les performances en temps r\u00e9el.<\/strong><\/p>\n<p>De nombreux facteurs sont d\u00e9terminants pour le vieillissement des cellules de batterie. Outre le vieillissement calendaire, qui est principalement d\u00e9termin\u00e9 par les temp\u00e9ratures de stockage et l&#8217;\u00e9tat de charge pendant le stockage, c&#8217;est surtout l&#8217;historique de tous les processus de charge et de d\u00e9charge avec les charges de courant et les temp\u00e9ratures qui se sont produites \u00e0 chaque fois qui est d\u00e9terminant. Il s&#8217;agit donc de nombreux facteurs d&#8217;influence variables sur de grandes p\u00e9riodes, raison pour laquelle la d\u00e9termination pr\u00e9cise de l&#8217;\u00e9tat de vieillissement est complexe et jusqu&#8217;\u00e0 pr\u00e9sent li\u00e9e \u00e0 des d\u00e9penses consid\u00e9rables. Dans ce contexte, les approches existantes se basent soit sur des simulations, qui repr\u00e9sentent une description simplifi\u00e9e du syst\u00e8me de batterie et du processus de d\u00e9composition, soit sur une extrapolation exp\u00e9rimentale de la dur\u00e9e de vie cyclique des cellules de la batterie. Dans ce cas, on d\u00e9termine la relation empirique entre l&#8217;imp\u00e9dance mesur\u00e9e d&#8217;une cellule et la capacit\u00e9 de la batterie.<\/p>\n<p>Pour la mod\u00e9lisation simul\u00e9e, il faut conna\u00eetre les processus d\u00e9taill\u00e9s pour chaque type de cellule. De plus, pour le transf\u00e9rer \u00e0 une nouvelle chimie de cellule, il faut refaire tout le processus de description, ce qui est co\u00fbteux. C&#8217;est \u00e9galement le cas pour l&#8217;extrapolation \u00e0 partir de mesures, car l&#8217;ensemble des mesures doit \u00eatre effectu\u00e9 pour chaque type de cellule \u00e0 d\u00e9crire et pour toutes les conditions environnementales existantes (temp\u00e9rature, profil de charge, etc.).<\/p>\n<p>Avec la nouvelle approche de d\u00e9veloppement pour la d\u00e9termination de la dur\u00e9e de vie, le syst\u00e8me de batterie re\u00e7oit une m\u00e9moire de tous les processus. Dans la nouvelle approche, la dur\u00e9e de vie des cellules de la batterie est d\u00e9crite \u00e0 l&#8217;aide d&#8217;un mod\u00e8le bas\u00e9 sur une connaissance limit\u00e9e de la chimie des cellules. Pour ce faire, des mod\u00e8les math\u00e9matiques de comportement non lin\u00e9aire avec des &#8220;effets de m\u00e9moire&#8221; (appel\u00e9s s\u00e9ries de Volterra) sont utilis\u00e9s pour d\u00e9crire les propri\u00e9t\u00e9s des cellules. Cette approche pr\u00e9sente l&#8217;avantage de faire d\u00e9pendre la sortie du syst\u00e8me de l&#8217;entr\u00e9e dans le syst\u00e8me \u00e0 tout moment, ce qui donne au syst\u00e8me une m\u00e9moire de tous les processus pr\u00e9c\u00e9dents, ce qui est indispensable pour d\u00e9crire le processus de vieillissement.<\/p>\n<p>L&#8217;\u00e9tape d\u00e9cisive est alors la mesure de l&#8217;imp\u00e9dance dynamique des cellules de la batterie pendant l&#8217;utilisation, c&#8217;est-\u00e0-dire pendant la charge ou la d\u00e9charge de la cellule. Il est alors possible de mesurer directement les param\u00e8tres math\u00e9matiques d\u00e9crivant le comportement des cellules. Cette repr\u00e9sentation math\u00e9matique permet ensuite de prendre en compte des \u00e9tats non mesur\u00e9s, ce qui rend possible la transposition \u00e0 d&#8217;autres conditions environnementales et \u00e0 d&#8217;autres chimies de cellules, c&#8217;est-\u00e0-dire la prise en compte de nouveaux types de batteries.<\/p>\n<p>La nouvelle m\u00e9thode offre non seulement la possibilit\u00e9 d&#8217;appliquer les r\u00e9sultats \u00e0 des types de cellules tr\u00e8s diff\u00e9rents (par ex. les batteries \u00e0 l&#8217;\u00e9tat solide) avec un minimum d&#8217;efforts, mais surtout l&#8217;avantage de pouvoir effectuer les mesures directement pendant l&#8217;utilisation d&#8217;une batterie, par ex. dans une voiture \u00e9lectrique. Il n&#8217;est pas n\u00e9cessaire de faire appel \u00e0 un laboratoire suppl\u00e9mentaire ou de limiter l&#8217;utilisation pour d\u00e9terminer l&#8217;\u00e2ge.<\/p>\n<p>L&#8217;impl\u00e9mentation dans le syst\u00e8me de gestion de la batterie permet donc d&#8217;obtenir toutes les donn\u00e9es n\u00e9cessaires au pronostic de la dur\u00e9e de vie pendant l&#8217;utilisation du syst\u00e8me. De plus, il est possible de d\u00e9velopper des strat\u00e9gies de charge optimis\u00e9es sur la base de ces donn\u00e9es afin d&#8217;augmenter la dur\u00e9e de vie totale du syst\u00e8me de batterie. Cela permet de r\u00e9duire les co\u00fbts de la dur\u00e9e de vie et d&#8217;augmenter la durabilit\u00e9 lors de l&#8217;utilisation d&#8217;un syst\u00e8me de batterie dans l&#8217;application.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Afin de pouvoir d\u00e9terminer l&#8217;\u00e9tat des cellules de batterie de mani\u00e8re plus pr\u00e9cise et sans devoir recourir \u00e0 un laboratoire, le Fraunhofer IFAM de Br\u00eame a perfectionn\u00e9 la d\u00e9termination de la r\u00e9sistance du courant alternatif au sein de la batterie au moyen de la spectroscopie d&#8217;imp\u00e9dance dynamique. Il est ainsi possible d&#8217;effectuer des mesures pendant [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[257,252],"class_list":["post-30051","post","type-post","status-publish","format-standard","hentry","category-non-classifie","tag-mobilite-infrastructure","tag-efficacite-energetique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plus de durabilit\u00e9 dans l&#039;\u00e9lectromobilit\u00e9 - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de durabilit\u00e9 dans l&#039;\u00e9lectromobilit\u00e9 - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Afin de pouvoir d\u00e9terminer l&#8217;\u00e9tat des cellules de batterie de mani\u00e8re plus pr\u00e9cise et sans devoir recourir \u00e0 un laboratoire, le Fraunhofer IFAM de Br\u00eame a perfectionn\u00e9 la d\u00e9termination de la r\u00e9sistance du courant alternatif au sein de la batterie au moyen de la spectroscopie d&#8217;imp\u00e9dance dynamique. Il est ainsi possible d&#8217;effectuer des mesures pendant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T08:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T12:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/04\/Nachhaltigkeit-Elektromobilitaet_1660x470.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nalini Schempp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/\"},\"author\":{\"name\":\"Nalini Schempp\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\"},\"headline\":\"Plus de durabilit\u00e9 dans l&#8217;\u00e9lectromobilit\u00e9\",\"datePublished\":\"2023-04-06T08:00:53+00:00\",\"dateModified\":\"2023-04-11T12:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/\"},\"wordCount\":799,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"keywords\":[\"Mobilit\u00e4t FR\",\"Produktion und Dienstleistung FR\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/\",\"name\":\"Plus de durabilit\u00e9 dans l'\u00e9lectromobilit\u00e9 - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\"},\"datePublished\":\"2023-04-06T08:00:53+00:00\",\"dateModified\":\"2023-04-11T12:00:48+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\",\"name\":\"Nalini Schempp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"caption\":\"Nalini Schempp\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plus de durabilit\u00e9 dans l'\u00e9lectromobilit\u00e9 - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Plus de durabilit\u00e9 dans l'\u00e9lectromobilit\u00e9 - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text]Afin de pouvoir d\u00e9terminer l&#8217;\u00e9tat des cellules de batterie de mani\u00e8re plus pr\u00e9cise et sans devoir recourir \u00e0 un laboratoire, le Fraunhofer IFAM de Br\u00eame a perfectionn\u00e9 la d\u00e9termination de la r\u00e9sistance du courant alternatif au sein de la batterie au moyen de la spectroscopie d&#8217;imp\u00e9dance dynamique. Il est ainsi possible d&#8217;effectuer des mesures pendant [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/","og_site_name":"Electrosuisse","article_published_time":"2023-04-06T08:00:53+00:00","article_modified_time":"2023-04-11T12:00:48+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/04\/Nachhaltigkeit-Elektromobilitaet_1660x470.jpg","type":"image\/png"}],"author":"Nalini Schempp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/"},"author":{"name":"Nalini Schempp","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08"},"headline":"Plus de durabilit\u00e9 dans l&#8217;\u00e9lectromobilit\u00e9","datePublished":"2023-04-06T08:00:53+00:00","dateModified":"2023-04-11T12:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/"},"wordCount":799,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"keywords":["Mobilit\u00e4t FR","Produktion und Dienstleistung FR"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/","name":"Plus de durabilit\u00e9 dans l'\u00e9lectromobilit\u00e9 - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website"},"datePublished":"2023-04-06T08:00:53+00:00","dateModified":"2023-04-11T12:00:48+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/fr\/plus-de-durabilite-dans-lelectromobilite\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08","name":"Nalini Schempp","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","caption":"Nalini Schempp"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/30051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/comments?post=30051"}],"version-history":[{"count":1,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/30051\/revisions"}],"predecessor-version":[{"id":30052,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/30051\/revisions\/30052"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/media?parent=30051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/categories?post=30051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/tags?post=30051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}