{"id":28793,"date":"2023-02-01T06:28:07","date_gmt":"2023-02-01T05:28:07","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/expert-talk-matter-und-leuchtstofflampenverbot\/"},"modified":"2023-02-28T06:23:22","modified_gmt":"2023-02-28T05:23:22","slug":"expert-talk-pour-la-premiere-fois-avec-traduction-simultanee","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/","title":{"rendered":"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Le 26 janvier dernier, Electrosuisse a offert la possibilit\u00e9 de suivre l\u2019un de ses \u00e9v\u00e9nements Expert Talk avec traduction simultan\u00e9e et pr\u00e9sentation traduite en fran\u00e7ais.[\/vc_column_text][vc_column_text]Au programme : l&#8217;introduction de la norme de connectivit\u00e9 Matter, qui doit garantir l&#8217;interop\u00e9rabilit\u00e9 entre les appareils smart home de diff\u00e9rents fabricants, ainsi que la future interdiction d&#8217;importation et de vente des lampes fluorescentes.<\/p>\n<p><a href=\"https:\/\/www.bulletin.ch\/fr\/news-detail\/deux-premieres-et-une-fin.html\" target=\"_blank\" rel=\"noopener\">Lire l\u2019article paru en ligne<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Le 26 janvier dernier, Electrosuisse a offert la possibilit\u00e9 de suivre l\u2019un de ses \u00e9v\u00e9nements Expert Talk avec traduction simultan\u00e9e et pr\u00e9sentation traduite en fran\u00e7ais.[\/vc_column_text][vc_column_text]Au programme : l&#8217;introduction de la norme de connectivit\u00e9 Matter, qui doit garantir l&#8217;interop\u00e9rabilit\u00e9 entre les appareils smart home de diff\u00e9rents fabricants, ainsi que la future interdiction d&#8217;importation et de vente [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[260,248],"class_list":["post-28793","post","type-post","status-publish","format-standard","hentry","category-non-classifie","tag-installation-electrique","tag-technique-du-batiment"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Le 26 janvier dernier, Electrosuisse a offert la possibilit\u00e9 de suivre l\u2019un de ses \u00e9v\u00e9nements Expert Talk avec traduction simultan\u00e9e et pr\u00e9sentation traduite en fran\u00e7ais.[\/vc_column_text][vc_column_text]Au programme : l&#8217;introduction de la norme de connectivit\u00e9 Matter, qui doit garantir l&#8217;interop\u00e9rabilit\u00e9 entre les appareils smart home de diff\u00e9rents fabricants, ainsi que la future interdiction d&#8217;importation et de vente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T05:28:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-28T05:23:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/electrosuisse-logo-1200x675-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anita Serafini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/\"},\"author\":{\"name\":\"Anita Serafini\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/0ef69aac34185528f3a6d17888410caf\"},\"headline\":\"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e\",\"datePublished\":\"2023-02-01T05:28:07+00:00\",\"dateModified\":\"2023-02-28T05:23:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/\"},\"wordCount\":104,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"keywords\":[\"Elektroinstallation FR\",\"Geb\u00e4udetechnik FR\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/\",\"name\":\"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\"},\"datePublished\":\"2023-02-01T05:28:07+00:00\",\"dateModified\":\"2023-02-28T05:23:22+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/0ef69aac34185528f3a6d17888410caf\",\"name\":\"Anita Serafini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b7b417c5e262b4d5423cd3f96595e0b5e8bacff15771d8b388b51c84ed55a54?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b7b417c5e262b4d5423cd3f96595e0b5e8bacff15771d8b388b51c84ed55a54?s=96&d=mm&r=g\",\"caption\":\"Anita Serafini\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text]Le 26 janvier dernier, Electrosuisse a offert la possibilit\u00e9 de suivre l\u2019un de ses \u00e9v\u00e9nements Expert Talk avec traduction simultan\u00e9e et pr\u00e9sentation traduite en fran\u00e7ais.[\/vc_column_text][vc_column_text]Au programme : l&#8217;introduction de la norme de connectivit\u00e9 Matter, qui doit garantir l&#8217;interop\u00e9rabilit\u00e9 entre les appareils smart home de diff\u00e9rents fabricants, ainsi que la future interdiction d&#8217;importation et de vente [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/","og_site_name":"Electrosuisse","article_published_time":"2023-02-01T05:28:07+00:00","article_modified_time":"2023-02-28T05:23:22+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/electrosuisse-logo-1200x675-1.png","type":"image\/png"}],"author":"Anita Serafini","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/"},"author":{"name":"Anita Serafini","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/0ef69aac34185528f3a6d17888410caf"},"headline":"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e","datePublished":"2023-02-01T05:28:07+00:00","dateModified":"2023-02-28T05:23:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/"},"wordCount":104,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"keywords":["Elektroinstallation FR","Geb\u00e4udetechnik FR"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/","name":"Expert Talk: pour la premi\u00e8re fois avec traduction simultan\u00e9e - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website"},"datePublished":"2023-02-01T05:28:07+00:00","dateModified":"2023-02-28T05:23:22+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/fr\/expert-talk-pour-la-premiere-fois-avec-traduction-simultanee\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/0ef69aac34185528f3a6d17888410caf","name":"Anita Serafini","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b7b417c5e262b4d5423cd3f96595e0b5e8bacff15771d8b388b51c84ed55a54?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b7b417c5e262b4d5423cd3f96595e0b5e8bacff15771d8b388b51c84ed55a54?s=96&d=mm&r=g","caption":"Anita Serafini"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/28793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/comments?post=28793"}],"version-history":[{"count":5,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/28793\/revisions"}],"predecessor-version":[{"id":29256,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/28793\/revisions\/29256"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/media?parent=28793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/categories?post=28793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/tags?post=28793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}