{"id":26186,"date":"2022-09-19T10:00:36","date_gmt":"2022-09-19T08:00:36","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=26186"},"modified":"2022-12-01T15:22:58","modified_gmt":"2022-12-01T14:22:58","slug":"un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/","title":{"rendered":"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>L&#8217;Institut de technologie de Karlsruhe et ITK Engineering viennent de mettre au point un capteur qui utilise une empreinte magn\u00e9tique pour d\u00e9terminer avec pr\u00e9cision la position des trains. Cela pourrait augmenter consid\u00e9rablement la capacit\u00e9 du r\u00e9seau ferroviaire existant.<\/strong><\/p>\n<p>En d\u00e9terminant de mani\u00e8re plus pr\u00e9cise et plus fiable la position d&#8217;un train sur une voie, les trains peuvent passer sur un tron\u00e7on \u00e0 des intervalles plus courts, ce qui permet d\u2019augmenter la capacit\u00e9 par kilom\u00e8tre de voie. Le fonctionnement du nouveau Magnetic Railway Onboard Sensor (Maros) est simple : une voie ferr\u00e9e en m\u00e9tal poss\u00e8de, elle aussi, une sorte d&#8217;empreinte digitale qui pr\u00e9sente un profil tr\u00e8s individuel \u00e0 chaque endroit. Le capteur Maros peut reconna\u00eetre cette empreinte avec pr\u00e9cision. Il est ainsi possible de localiser les trains dans le monde entier de mani\u00e8re pr\u00e9cise et continue.<\/p>\n<p>Pour ce faire, le capteur, fix\u00e9 sur le dessous du v\u00e9hicule, g\u00e9n\u00e8re un champ \u00e9lectromagn\u00e9tique qui est influenc\u00e9 par les mat\u00e9riaux ferromagn\u00e9tiques des rails ou du mat\u00e9riel de fixation des rails, et mesure comment le champ \u00e9lectromagn\u00e9tique est modifi\u00e9. Il est ainsi possible d&#8217;attribuer une empreinte \u00e9lectromagn\u00e9tique \u00e0 chaque tron\u00e7on de voie. Pour pouvoir attribuer une signature de lieu individuelle \u00e0 une position g\u00e9ographique, il faut un backend logiciel incluant des algorithmes intelligents. Ainsi, chaque ligne de chemin de fer doit \u00eatre parcourue et mesur\u00e9e au moins une fois avant que les donn\u00e9es recueillies puissent \u00eatre superpos\u00e9es aux informations cartographiques de la ligne de train. Chaque train suivant peut alors \u00eatre localis\u00e9 avec pr\u00e9cision.<\/p>\n<p>Les solutions utilis\u00e9es aujourd&#8217;hui dans le monde entier pour d\u00e9terminer la position des trains pr\u00e9sentent toutes des lacunes que le capteur Maros permet d&#8217;\u00e9viter : les supports d&#8217;information (balises) install\u00e9s sur les voies sont fiables, mais co\u00fbteux. Les syst\u00e8mes de cam\u00e9ras ont l&#8217;inconv\u00e9nient de ne fonctionner que de mani\u00e8re limit\u00e9e la nuit ou en cas de chute de neige. Les signaux GPS atteignent leurs limites dans les tunnels, les vall\u00e9es de montagne ou les canyons urbains. De plus, ils ne permettent pas de savoir avec certitude quelle voie est emprunt\u00e9e parmi plusieurs voies adjacentes. Or, cette localisation pr\u00e9cise est absolument n\u00e9cessaire pour l&#8217;exploitation ferroviaire et peut \u00eatre obtenue gr\u00e2ce au capteur Maros. La localisation est donc plus pr\u00e9cise que jamais, moins co\u00fbteuse que d&#8217;autres technologies et utilisable dans le monde entier sur tous les rails en acier.<\/p>\n<p>Les chercheurs ont pu prouver que le capteur fonctionne en le mettant en \u0153uvre sur certaines parties des r\u00e9seaux ferroviaires ouest et nord \u00e0 proximit\u00e9 de Vienne. Le capteur devrait \u00eatre disponible sur le march\u00e9 d&#8217;ici d\u00e9but 2025.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]L&#8217;Institut de technologie de Karlsruhe et ITK Engineering viennent de mettre au point un capteur qui utilise une empreinte magn\u00e9tique pour d\u00e9terminer avec pr\u00e9cision la position des trains. Cela pourrait augmenter consid\u00e9rablement la capacit\u00e9 du r\u00e9seau ferroviaire existant. En d\u00e9terminant de mani\u00e8re plus pr\u00e9cise et plus fiable la position d&#8217;un train sur une voie, les [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[257],"class_list":["post-26186","post","type-post","status-publish","format-standard","hentry","category-non-classifie","tag-mobilite-infrastructure"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]L&#8217;Institut de technologie de Karlsruhe et ITK Engineering viennent de mettre au point un capteur qui utilise une empreinte magn\u00e9tique pour d\u00e9terminer avec pr\u00e9cision la position des trains. Cela pourrait augmenter consid\u00e9rablement la capacit\u00e9 du r\u00e9seau ferroviaire existant. En d\u00e9terminant de mani\u00e8re plus pr\u00e9cise et plus fiable la position d&#8217;un train sur une voie, les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-19T08:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-01T14:22:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/12\/Neuer-Sensor_1660x470.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nalini Schempp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/\"},\"author\":{\"name\":\"Nalini Schempp\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\"},\"headline\":\"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne\",\"datePublished\":\"2022-09-19T08:00:36+00:00\",\"dateModified\":\"2022-12-01T14:22:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/\"},\"wordCount\":510,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"keywords\":[\"Mobilit\u00e4t FR\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/\",\"name\":\"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\"},\"datePublished\":\"2022-09-19T08:00:36+00:00\",\"dateModified\":\"2022-12-01T14:22:58+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\",\"name\":\"Nalini Schempp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"caption\":\"Nalini Schempp\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text]L&#8217;Institut de technologie de Karlsruhe et ITK Engineering viennent de mettre au point un capteur qui utilise une empreinte magn\u00e9tique pour d\u00e9terminer avec pr\u00e9cision la position des trains. Cela pourrait augmenter consid\u00e9rablement la capacit\u00e9 du r\u00e9seau ferroviaire existant. En d\u00e9terminant de mani\u00e8re plus pr\u00e9cise et plus fiable la position d&#8217;un train sur une voie, les [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/","og_site_name":"Electrosuisse","article_published_time":"2022-09-19T08:00:36+00:00","article_modified_time":"2022-12-01T14:22:58+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/12\/Neuer-Sensor_1660x470.jpg","type":"image\/png"}],"author":"Nalini Schempp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/"},"author":{"name":"Nalini Schempp","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08"},"headline":"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne","datePublished":"2022-09-19T08:00:36+00:00","dateModified":"2022-12-01T14:22:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/"},"wordCount":510,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"keywords":["Mobilit\u00e4t FR"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/","name":"Un nouveau capteur permet de faire circuler plus de trains sur une m\u00eame ligne - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website"},"datePublished":"2022-09-19T08:00:36+00:00","dateModified":"2022-12-01T14:22:58+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/fr\/un-nouveau-capteur-permet-de-faire-circuler-plus-de-trains-sur-une-meme-ligne\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08","name":"Nalini Schempp","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","caption":"Nalini Schempp"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/26186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/comments?post=26186"}],"version-history":[{"count":0,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/26186\/revisions"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/media?parent=26186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/categories?post=26186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/tags?post=26186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}