{"id":25430,"date":"2022-02-15T10:00:17","date_gmt":"2022-02-15T09:00:17","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?p=25430"},"modified":"2022-12-01T13:58:00","modified_gmt":"2022-12-01T12:58:00","slug":"le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions","status":"publish","type":"post","link":"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/","title":{"rendered":"Le vent et le soleil contre l&#8217;\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>Plus de pompes \u00e0 chaleur dans les b\u00e2timents et plus de voitures \u00e9lectriques sur les routes entra\u00eeneront \u00e0 l&#8217;avenir une augmentation de la consommation d&#8217;\u00e9lectricit\u00e9. Pour couvrir ces besoins croissants, la Suisse est tributaire d&#8217;importations d&#8217;\u00e9lectricit\u00e9, qui pr\u00e9sentent toutefois souvent une forte empreinte carbone, car elles proviennent de centrales \u00e0 gaz ou \u00e0 charbon.<\/strong><\/p>\n<p>Dans une nouvelle \u00e9tude, des chercheurs de l&#8217;Empa et de l&#8217;Universit\u00e9 de Gen\u00e8ve montrent, \u00e0 l&#8217;aide de diff\u00e9rents sc\u00e9narios, comment la Suisse peut r\u00e9duire ces importations d&#8217;\u00e9lectricit\u00e9 charg\u00e9es de CO2 en d\u00e9veloppant de mani\u00e8re diversifi\u00e9e les \u00e9nergies renouvelables.<\/p>\n<p>Le point de d\u00e9part de la strat\u00e9gie climatique \u00e0 long terme de la Suisse est l&#8217;objectif net z\u00e9ro pour 2050, que le Conseil f\u00e9d\u00e9ral a d\u00e9cid\u00e9 en ao\u00fbt 2019. De nombreuses strat\u00e9gies sur cette voie impliquent le remplacement des combustibles fossiles par de l&#8217;\u00e9lectricit\u00e9 &#8211; dans la mobilit\u00e9 sous forme de v\u00e9hicules \u00e9lectriques et dans le b\u00e2timent sous forme de pompes \u00e0 chaleur. En Suisse, l&#8217;\u00e9lectricit\u00e9 n\u00e9cessaire provient aujourd&#8217;hui en grande partie de centrales nucl\u00e9aires et hydrauliques &#8211; des technologies \u00e0 faible empreinte carbone. Mais si l&#8217;on consid\u00e8re l&#8217;ensemble de l&#8217;Europe, la situation est diff\u00e9rente : On estime que les centrales \u00e9lectriques fossiles sont responsables d&#8217;environ 25% de l&#8217;ensemble des \u00e9missions des gaz \u00e0 effet de serre en Europe.<\/p>\n<p>Aujourd&#8217;hui d\u00e9j\u00e0, la Suisse est tributaire des importations d&#8217;\u00e9lectricit\u00e9 des pays voisins. La part de l&#8217;\u00e9lectricit\u00e9 import\u00e9e repr\u00e9sente environ 11%. Si l&#8217;on veut maintenir la charge en CO2 du mix \u00e9lectrique suisse \u00e0 un bas niveau, il est donc n\u00e9cessaire de regarder de plus pr\u00e8s ces importations. Dans une nouvelle \u00e9tude, les importations d&#8217;\u00e9lectricit\u00e9 ont \u00e9t\u00e9 analys\u00e9es heure par heure et les \u00e9missions de CO2 directes et indirectes de la production d&#8217;\u00e9lectricit\u00e9 ont \u00e9t\u00e9 prises en compte. Alors que l&#8217;\u00e9lectricit\u00e9 produite en Suisse g\u00e9n\u00e8re environ 40g d&#8217;\u00e9quivalents CO2 par kilowattheure, la moyenne de l&#8217;ensemble du mix \u00e9lectrique suisse &#8211; importations comprises &#8211; se situe autour de 108g.<\/p>\n<h3>Remplacement de l&#8217;\u00e9lectricit\u00e9 nucl\u00e9aire<\/h3>\n<p>En raison de l&#8217;augmentation de l&#8217;\u00e9lectrification, les chercheurs pr\u00e9voient un besoin suppl\u00e9mentaire en \u00e9lectricit\u00e9 d&#8217;environ 12 TWh par an. Cela repr\u00e9sente bien 20% de plus que ce que nous consommons d\u00e9j\u00e0 aujourd&#8217;hui. Comme le Conseil f\u00e9d\u00e9ral pr\u00e9voit de sortir progressivement de l&#8217;\u00e9nergie nucl\u00e9aire, la Suisse doit remplacer l&#8217;\u00e9lectricit\u00e9 nucl\u00e9aire. Ce remplacement se fait par des \u00e9nergies renouvelables, qui n&#8217;apparaissent pas de mani\u00e8re r\u00e9guli\u00e8re et influencent donc \u00e0 leur tour consid\u00e9rablement la quantit\u00e9 et le moment des importations d&#8217;\u00e9lectricit\u00e9.<\/p>\n<p>Dans ce contexte, les chercheurs ont d\u00e9velopp\u00e9 diff\u00e9rents sc\u00e9narios et analys\u00e9 la composition du mix \u00e9lectrique suisse \u00e0 l&#8217;avenir, afin de minimiser les importations et donc les \u00e9missions des gaz \u00e0 effet de serre li\u00e9es \u00e0 l&#8217;\u00e9lectricit\u00e9. L&#8217;\u00e9tude montre que la part d&#8217;\u00e9lectricit\u00e9 import\u00e9e dans le mix \u00e9lectrique suisse augmentera dans tous les cas, et donc aussi les \u00e9missions de CO2. Mais malgr\u00e9 cette augmentation des \u00e9missions &#8220;import\u00e9es&#8221;, l&#8217;\u00e9lectrification croissante du chauffage et de la mobilit\u00e9 permettra de r\u00e9duire jusqu&#8217;\u00e0 45% les \u00e9missions de gaz \u00e0 effet de serre dans l&#8217;ensemble du syst\u00e8me \u00e9nerg\u00e9tique suisse.<\/p>\n<h3>Le vent contre la p\u00e9nurie d&#8217;\u00e9lectricit\u00e9 en hiver &#8211; et les technologies &#8220;Power-to-X&#8221;<\/h3>\n<p>C&#8217;est en hiver que la Suisse continuera \u00e0 d\u00e9pendre le plus des importations d&#8217;\u00e9lectricit\u00e9 en raison des rendements plus faibles du photovolta\u00efque. Le sc\u00e9nario qui a obtenu les meilleurs r\u00e9sultats en termes de r\u00e9duction des \u00e9missions dans l&#8217;\u00e9tude pr\u00e9voit donc, outre un d\u00e9veloppement de l&#8217;\u00e9nergie solaire \u00e0 25 TWh (contre 2,7 TWh actuellement), une part importante d&#8217;\u00e9nergie \u00e9olienne d&#8217;environ 12 TWh (contre 0,1 TWh actuellement).<\/p>\n<p>Dans tous les sc\u00e9narios calcul\u00e9s, il faut s&#8217;attendre \u00e0 d&#8217;importants exc\u00e9dents d&#8217;\u00e9lectricit\u00e9 en \u00e9t\u00e9 en raison du d\u00e9veloppement du photovolta\u00efque. Selon les chercheurs, le plus grand potentiel pour transf\u00e9rer ces exc\u00e9dents en hiver r\u00e9side dans les technologies &#8220;Power-to-X&#8221;, qui permettent de transformer l&#8217;\u00e9lectricit\u00e9 exc\u00e9dentaire en vecteurs d&#8217;\u00e9nergie chimique stockables tels que l&#8217;hydrog\u00e8ne ou le m\u00e9thane synth\u00e9tique, ainsi que dans les accumulateurs thermiques tels que les champs de sondes g\u00e9othermiques.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Plus de pompes \u00e0 chaleur dans les b\u00e2timents et plus de voitures \u00e9lectriques sur les routes entra\u00eeneront \u00e0 l&#8217;avenir une augmentation de la consommation d&#8217;\u00e9lectricit\u00e9. Pour couvrir ces besoins croissants, la Suisse est tributaire d&#8217;importations d&#8217;\u00e9lectricit\u00e9, qui pr\u00e9sentent toutefois souvent une forte empreinte carbone, car elles proviennent de centrales \u00e0 gaz ou \u00e0 charbon. Dans [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[244],"class_list":["post-25430","post","type-post","status-publish","format-standard","hentry","category-non-classifie","tag-energie-et-reseaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le vent et le soleil contre l&#039;\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le vent et le soleil contre l&#039;\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Plus de pompes \u00e0 chaleur dans les b\u00e2timents et plus de voitures \u00e9lectriques sur les routes entra\u00eeneront \u00e0 l&#8217;avenir une augmentation de la consommation d&#8217;\u00e9lectricit\u00e9. Pour couvrir ces besoins croissants, la Suisse est tributaire d&#8217;importations d&#8217;\u00e9lectricit\u00e9, qui pr\u00e9sentent toutefois souvent une forte empreinte carbone, car elles proviennent de centrales \u00e0 gaz ou \u00e0 charbon. Dans [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-15T09:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-01T12:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/11\/Importstrom_1660x470.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nalini Schempp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/\"},\"author\":{\"name\":\"Nalini Schempp\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\"},\"headline\":\"Le vent et le soleil contre l&#8217;\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions\",\"datePublished\":\"2022-02-15T09:00:17+00:00\",\"dateModified\":\"2022-12-01T12:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/\"},\"wordCount\":770,\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"keywords\":[\"Energieversorgung FR\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/\",\"name\":\"Le vent et le soleil contre l'\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\"},\"datePublished\":\"2022-02-15T09:00:17+00:00\",\"dateModified\":\"2022-12-01T12:58:00+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08\",\"name\":\"Nalini Schempp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g\",\"caption\":\"Nalini Schempp\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le vent et le soleil contre l'\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Le vent et le soleil contre l'\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text]Plus de pompes \u00e0 chaleur dans les b\u00e2timents et plus de voitures \u00e9lectriques sur les routes entra\u00eeneront \u00e0 l&#8217;avenir une augmentation de la consommation d&#8217;\u00e9lectricit\u00e9. Pour couvrir ces besoins croissants, la Suisse est tributaire d&#8217;importations d&#8217;\u00e9lectricit\u00e9, qui pr\u00e9sentent toutefois souvent une forte empreinte carbone, car elles proviennent de centrales \u00e0 gaz ou \u00e0 charbon. Dans [&hellip;]","og_url":"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/","og_site_name":"Electrosuisse","article_published_time":"2022-02-15T09:00:17+00:00","article_modified_time":"2022-12-01T12:58:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/11\/Importstrom_1660x470.jpg","type":"image\/png"}],"author":"Nalini Schempp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/#article","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/"},"author":{"name":"Nalini Schempp","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08"},"headline":"Le vent et le soleil contre l&#8217;\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions","datePublished":"2022-02-15T09:00:17+00:00","dateModified":"2022-12-01T12:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/"},"wordCount":770,"publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"keywords":["Energieversorgung FR"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/","name":"Le vent et le soleil contre l'\u00e9lectricit\u00e9 import\u00e9e riche en \u00e9missions - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website"},"datePublished":"2022-02-15T09:00:17+00:00","dateModified":"2022-12-01T12:58:00+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/fr\/le-vent-et-le-soleil-contre-lelectricite-importee-riche-en-emissions\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."},{"@type":"Person","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/8770e16f2c82936b086c9d1c1c004c08","name":"Nalini Schempp","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2e8b75d6e8fb1fd661220d625f7823d02404773b42d5decd9a0b3dd5a2a1fe6?s=96&d=mm&r=g","caption":"Nalini Schempp"}}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/25430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/comments?post=25430"}],"version-history":[{"count":0,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/posts\/25430\/revisions"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/media?parent=25430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/categories?post=25430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/tags?post=25430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}