{"id":21747,"date":"2022-04-08T07:09:06","date_gmt":"2022-04-08T05:09:06","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?page_id=21747"},"modified":"2024-04-22T09:45:35","modified_gmt":"2024-04-22T07:45:35","slug":"mobilite","status":"publish","type":"page","link":"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/","title":{"rendered":"Mobilit\u00e9"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text el_class=&#8221;lead&#8221;]Une mobilit\u00e9 intelligente, fiable et exempte d\u2019\u00e9missions constitue un facteur cl\u00e9 afin de concevoir une consommation d\u2019\u00e9nergie d\u2019une mani\u00e8re compatible avec les objectifs climatiques dans ce secteur. Pour ce faire, notre association et sa soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e e-mobile mettent une large gamme d\u2019infrastructures de recharge \u00e0 la disposition des exploitants et des utilisateurs. Ainsi, vingt-trois stations de recharge disponibles sur le march\u00e9 en Suisse et dix syst\u00e8mes de gestion de la charge sont employ\u00e9s et expliqu\u00e9s. En outre, e-mobile propose des formations et des expos\u00e9s portant sur le th\u00e8me de la mobilit\u00e9 \u00e9lectrique.[\/vc_column_text][vc_column_text]<strong>Vous trouverez toutes les informations sur les v\u00e9hicules, l&#8217;infrastructure et les publications relatives \u00e0 la mobilit\u00e9 efficace sur <a href=\"https:\/\/www.e-mobile.ch\/de\/\" target=\"_blank\" rel=\"noopener\">e-mobile.ch<\/a>.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=&#8221;courses&#8221;][vc_column][vc_column_text]<\/p>\n<h2>Manifestations<\/h2>\n<p>[\/vc_column_text]<div class=\"wpb_carousel_column wpb_carousel_column--event wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"event_container\"><div class=\"owl-carousel owl-theme\"><\/div><\/div><\/div><\/div><div class=\"wpb_button_column wpb_content_element wpb_content_element--left\"><div class=\"wpb_wrapper\"><div class=\"button button--ghost\"><a href=\"https:\/\/www.e-mobile.ch\/fr\/evenements\/\" target=\"_blank\" >Calendrier des \u00e9v\u00e9nements e-mobile<\/a><\/div><\/div><\/div><div class=\"wpb_button_column wpb_content_element wpb_content_element--left\"><div class=\"wpb_wrapper\"><div class=\"button button--ghost\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/tous-les-vnements\/\">Aper\u00e7u et informations compl\u00e9mentaires sur les manifestations<\/a><\/div><\/div><\/div><div class=\"wpb_document_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"document document--pdf\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/12\/Veranstaltungsuebersicht_Energietechnik_Informationstechnik_2023_Flyer_A5.pdf\" target=\"_blank\" rel=\"noopener\">Manifestations ET et IT<\/a><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row el_id=&#8221;engineering&#8221;][vc_column][vc_column_text]<\/p>\n<h2>Engineering<\/h2>\n<p>[\/vc_column_text]<div class=\"wpb_text_image_column wpb_content_element \"><div class=\"wpb_wrapper\"><div class=\"row reverse middle-lg\"><div class=\"col-sm-6 col-xs-12\"><div class=\"picture_container\"><picture><source srcset=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2019\/10\/Electrosuisse_Eisenbahntunnel-585x300.jpg\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2019\/10\/Electrosuisse_Eisenbahntunnel-585x300.jpg\" alt=\"S\u00e9curit\u00e9 sur les routes nationales et dans les tunnels ferroviaires\" \/><\/picture><\/div><\/div><div class=\"col-sm-6 col-xs-12\"><h3>S\u00e9curit\u00e9 sur les routes nationales et dans les tunnels ferroviaires<\/h3><p>Nos essais de produits, nos contr\u00f4les de la qualit\u00e9, nos contr\u00f4les de r\u00e9ception et nos <a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/ingenierie\/realisation\/concept-de-securite\/\">concepts de s\u00e9curit\u00e9<\/a> nous permettent d\u2019assurer la s\u00e9curit\u00e9 sur les routes nationales et dans les tunnels ferroviaires.<\/p>\n<div class=\"button button--normal\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/controles\/routes-nationales-et-tunnels-ferroviaires\/\">En savoir plus<\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_text_image_column wpb_content_element \"><div class=\"wpb_wrapper\"><div class=\"row middle-lg\"><div class=\"col-sm-6 col-xs-12\"><div class=\"picture_container\"><picture><source srcset=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2019\/06\/Electrosuisse_Power_Quality_Netzqualitaet_iStock-588367166_mobile-585x400.jpg\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2019\/06\/Electrosuisse_Power_Quality_Netzqualitaet_iStock-588367166_mobile-585x400.jpg\" alt=\"Qualit\u00e9 de l'\u00e9nergie\" \/><\/picture><\/div><\/div><div class=\"col-sm-6 col-xs-12\"><h3>Qualit\u00e9 de l'\u00e9nergie<\/h3><\/p>\n<h5>Optimiser la qualit\u00e9 et l\u2019exploitation du r\u00e9seau<\/h5>\n<p>Les \u00e9quipements \u00e9lectriques ne sauraient influencer n\u00e9gativement les autres syst\u00e8mes ou installations ni entraver l\u2019approvisionnement en \u00e9lectricit\u00e9 durant l\u2019exploitation normale, processus de commutation compris.<\/p>\n<p>Nos sp\u00e9cialistes vous soutiennent lors de toute perturbation du r\u00e9seau.<\/p>\n<div class=\"button button--normal\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/engineering\/qualite-energie\/\">En savoir plus<\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_gap_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"gap gap--big\"><\/div><\/div><\/div>[vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_id=&#8221;products&#8221;][vc_column][vc_column_text]<\/p>\n<h2>Produits<\/h2>\n<p>[\/vc_column_text]<div class=\"wpb_text_image_column wpb_content_element \"><div class=\"wpb_wrapper\"><div class=\"row reverse middle-lg\"><div class=\"col-sm-6 col-xs-12\"><div class=\"picture_container\"><picture><source srcset=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2021\/07\/Electrosuisse_Artmap_E-Mobile_Titelseite_fr_585x500-585x500.jpg\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2021\/07\/Electrosuisse_Artmap_E-Mobile_Titelseite_fr_585x500-585x500.jpg\" alt=\"ART-MAP: e-mobile\" \/><\/picture><\/div><\/div><div class=\"col-sm-6 col-xs-12\"><h3>ART-MAP: e-mobile<\/h3><\/p>\n<h5>La mobilit\u00e9 \u00e9lectrique &#8211; la propulsion de demain<\/h5>\n<p>L&#8217;artmap\u00ae d&#8217;Electrosuisse se caract\u00e9rise par le fait qu&#8217;elle pr\u00e9sente des contenus complexes de mani\u00e8re graphique et facilement compr\u00e9hensible sur deux pages A3.<\/p>\n<div class=\"button button--normal\"><a href=\"https:\/\/www.e-mobile.ch\/wp-content\/uploads\/2022\/02\/EL_Emobile_Broschuer_fr-WEB.pdf\" target=\"_blank\" rel=\"noopener\">T\u00e9l\u00e9chargement<\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_text_image_column wpb_content_element \"><div class=\"wpb_wrapper\"><div class=\"row middle-lg\"><div class=\"col-sm-6 col-xs-12\"><div class=\"picture_container\"><picture><source srcset=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/04\/Der-Antrieb-der-Zukunft_585x500-585x500.jpg\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/04\/Der-Antrieb-der-Zukunft_585x500-585x500.jpg\" alt=\"La mobilit\u00e9 \u00e9lectrique \u2013 la propulsion de demain\" \/><\/picture><\/div><\/div><div class=\"col-sm-6 col-xs-12\"><h3>La mobilit\u00e9 \u00e9lectrique \u2013 la propulsion de demain<\/h3><p>Dieses Buch unterst\u00fctzt Elektroplaner*innen bei der Planung von Anlagen, damit diese sicher und zukunftsgerichtet betrieben werden k\u00f6nnen.<\/p>\n<p>Das Buch greift verschiedene Aspekte auf, wie Anforderungen an Planende, Planungsprozess, Kosten und Kostenmanagement, Hilfsmittel und vieles mehr.<\/p>\n<div class=\"button button--normal\"><a href=\"https:\/\/shop.electrosuisse.ch\/fr\/DV-BROEMOBI-F-359333.html\" target=\"_blank\" rel=\"noopener\">Jetzt kaufen<\/a><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row el_id=&#8221;news&#8221;][vc_column][vc_column_text]<\/p>\n<h2>Actualit\u00e9s et articles sp\u00e9cialis\u00e9s<\/h2>\n<p>[\/vc_column_text]<div class=\"wpb_news_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"news_container\"><div class=\"owl-carousel owl-theme\"><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/news-detail\/l-optimisation-du-systeme-une-condition-prealable.html\" class=\"full\"  target=\"_blank\">L\u2019optimisation du syst\u00e8me, une condition pr\u00e9alable<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Fahrzeuge-von-DPD_362x218.png\" alt=\"L\u2019optimisation du syst\u00e8me, une condition pr\u00e9alable\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">12 mai 2025<\/span><h3>L\u2019optimisation du syst\u00e8me, une condition pr\u00e9alable<\/h3><p>DPD souhaite \u00e9lectrifier l\u2019ensemble de sa flotte marchande d\u2019ici 2035. L\u2019infrastructure de douze sites doit \u00eatre parfaitement d\u00e9velopp\u00e9e sur le plan \u00e9conomique. Un projet de recherche soutenu par l\u2019Office f\u00e9d\u00e9ral de l\u2019\u00e9nergie teste actuellement la mani\u00e8re dont cela pourrait \u00eatre possible, en s\u2019appuyant sur l\u2019exemple du site Wolf de B\u00e2le.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-electrosuisse-2024\/\" class=\"full\">Focus Salaire Electrosuisse 2024<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/11\/Lohnradar24_Keyvisual_768x300-585x300.png\" alt=\"Focus Salaire Electrosuisse 2024\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">18 novembre 2024<\/span><h3>Focus Salaire Electrosuisse 2024<\/h3><p>La cinqui\u00e8me \u00e9dition de notre magazine \u00ab Focus Salaire \u00bb vient de para\u00eetre. Elle montre clairement que la formation initiale, la formation continue et l\u2019exp\u00e9rience professionnelle sont payantes. Les avantages d\u2019une formation continue en gestion d\u2019entreprise sont particuli\u00e8rement manifestes. L\u2019\u00e9tude fournit \u00e9galement des informations int\u00e9ressantes sur le th\u00e8me de l\u2019internationalit\u00e9.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/3d-crashtests\/\" class=\"full\">Technique de mesure 3D innovante pour les crash-tests<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/10\/crashtest_362x218.png\" alt=\"Technique de mesure 3D innovante pour les crash-tests\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">1<sup>er<\/sup> novembre 2024<\/span><h3>Technique de mesure 3D innovante pour les crash-tests<\/h3><p>L\u2019Institut Fraunhofer IOF a d\u00e9velopp\u00e9 un syst\u00e8me 3D \u00e0 grande vitesse permettant de visualiser les d\u00e9formations \u00e0 l'int\u00e9rieur des v\u00e9hicules lors de crash-tests \u2013 et pour la premi\u00e8re fois, m\u00eame dans des zones difficiles d'acc\u00e8s.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/revolution-au-sein-de-la-mobilite\/\" class=\"full\">R\u00e9volution au sein de la mobilit\u00e9<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/05\/Wechselrichter_362x218.png\" alt=\"R\u00e9volution au sein de la mobilit\u00e9\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">15 mai 2024<\/span><h3>R\u00e9volution au sein de la mobilit\u00e9<\/h3><p>L'Institut Fraunhofer IZM d\u00e9veloppe un onduleur innovant pour v\u00e9hicules \u00e9lectriques avec des transistors en carbure de silicium et un refroidissement en cuivre 3D. Cela am\u00e9liore les performances, r\u00e9duit la chaleur et les co\u00fbts.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/focus-salaire-2024-internationalite\/\" class=\"full\">Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/03\/Lohnradar-585x500-1.jpg\" alt=\"Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">7 mars 2024<\/span><h3>Focus salaire 2024 \u2013 \u00abInternationalit\u00e9\u00bb<\/h3><p>Participez \u00e0 notre nouvelle enqu\u00eate pour le Focus Salaire Electrosuisse 2024 !<br \/>\r\nSaisissez l'occasion, remplissez le questionnaire et profitez des r\u00e9sultats !<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/revolution-dans-la-croissance-des-cristaux-un-systeme-laser-de-20-kw-pour-des-semi-conducteurs-ultrapurs\/\" class=\"full\">R\u00e9volution dans la croissance des cristaux<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/02\/LaserKristalle_NL_Vorschau.png\" alt=\"R\u00e9volution dans la croissance des cristaux\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">1<sup>er<\/sup> mars 2024<\/span><h3>R\u00e9volution dans la croissance des cristaux<\/h3><p>L\u2019Institut Fraunhofer ILT a d\u00e9velopp\u00e9 un syst\u00e8me laser de 20 kW pour la fabrication de cristaux semi-conducteurs ultrapurs gr\u00e2ce au proc\u00e9d\u00e9 de zone flottante \u00e0 diode laser. Cela permet de produire des cristaux plus grands et plus purs sans contamination par le creuset, un progr\u00e8s pour l'\u00e9lectronique et le photovolta\u00efque.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/concevoir-les-moteurs-electriques-pour-leconomie-circulaire\/\" class=\"full\">Concevoir les moteurs \u00e9lectriques pour l&#8217;\u00e9conomie circulaire<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2024\/01\/KW2_Elektromotor_Vorschau.jpg\" alt=\"Concevoir les moteurs \u00e9lectriques pour l&#8217;\u00e9conomie circulaire\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">11 janvier 2024<\/span><h3>Concevoir les moteurs \u00e9lectriques pour l&#8217;\u00e9conomie circulaire<\/h3><p>Dans le cadre du projet REASSERT, des chercheurs du Frauenhofer IPA d\u00e9veloppent de nouvelles approches pour les moteurs \u00e9lectriques, en mettant l\u2019accent sur la r\u00e9paration, le reconditionnement et la r\u00e9utilisation ainsi que sur l'\u00e9laboration de designs innovants pour une \u00e9conomie circulaire durable.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/de-zero-a-cent-en-0956-seconde\/\" class=\"full\">De z\u00e9ro \u00e0 cent en 0,956 seconde<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/12\/E-Bolide_585x500.jpg\" alt=\"De z\u00e9ro \u00e0 cent en 0,956 seconde\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">21 septembre 2023<\/span><h3>De z\u00e9ro \u00e0 cent en 0,956 seconde<\/h3><p>Avec \u00abMythen\u00bb, la voiture de course \u00e9lectrique qu\u2019ils ont construite de leurs propres mains, des \u00e9tudiants de l\u2019\u00c9cole polytechnique f\u00e9d\u00e9rale de Zurich (ETH Z\u00fcrich) et de la Haute \u00e9cole de Lucerne ont battu le record mondial d'acc\u00e9l\u00e9ration. Il n\u2019a fallu au bolide que 0,956 s et 12,3 m pour passer de 0 \u00e0 100 km\/h.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/fr\/nouvelles-technologies-pour-le-demantelement-des-batteries-automobiles\/\" class=\"full\">Nouvelles technologies pour le d\u00e9mant\u00e8lement des batteries automobiles<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/05\/Demontage_585x500-585x500.jpg\" alt=\"Nouvelles technologies pour le d\u00e9mant\u00e8lement des batteries automobiles\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">26 mai 2023<\/span><h3>Nouvelles technologies pour le d\u00e9mant\u00e8lement des batteries automobiles<\/h3><p>La d\u00e9cision du Parlement europ\u00e9en sur la fin des v\u00e9hicules \u00e0 combustion \u00e0 partir de 2035 l'a scell\u00e9 : L'avenir de l'industrie automobile r\u00e9side dans l'\u00e9lectromobilit\u00e9. Mais comme un syst\u00e8me de batterie n'a qu'une dur\u00e9e de vie moyenne d'une dizaine d'ann\u00e9es, la montagne de batteries usag\u00e9es ne cesse de cro\u00eetre et avec elle le probl\u00e8me de l'\u00e9limination et du recyclage des composants \u00e9lectriques.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_gap_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"gap gap--small\"><\/div><\/div><\/div>[vc_column_text]<\/p>\n<h4>Articles sur bulletin.ch<\/h4>\n<p>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/www.bulletin.ch\/fr\/themes\/category\/mobilite.html\" target=\"_blank\" rel=\"noopener\">bulletin.ch #mobilite<\/a>[\/vc_column_text]<div class=\"wpb_gap_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"gap gap--small\"><\/div><\/div><\/div>[vc_column_text]<\/p>\n<h2>Newsflash<\/h2>\n<p>[\/vc_column_text][vc_column_text]Vous \u00eates int\u00e9ress\u00e9 par notre newsflash th\u00e9matique \u00ab Mobilit\u00e9 \u00bb ?<\/p>\n<p>Inscrivez-vous d\u00e8s maintenant :[\/vc_column_text]<div class=\"wpb_button_column wpb_content_element wpb_content_element--left\"><div class=\"wpb_wrapper\"><div class=\"button button--ghost\"><a href=\"https:\/\/subscribe.newsletter2go.com\/?n2g=hqfmsc8j-cg2b8hn7-f9y&_ga=2.140955442.1260104048.1648205176-1145216005.1607948334\" target=\"_blank\" >Inscription au Newsflash \u00ab Mobilit\u00e9 \u00bb<\/a><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text el_class=&#8221;lead&#8221;]Une mobilit\u00e9 intelligente, fiable et exempte d\u2019\u00e9missions constitue un facteur cl\u00e9 afin de concevoir une consommation d\u2019\u00e9nergie d\u2019une mani\u00e8re compatible avec les objectifs climatiques dans ce secteur. Pour ce faire, notre association et sa soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e e-mobile mettent une large gamme d\u2019infrastructures de recharge \u00e0 la disposition des exploitants et des utilisateurs. Ainsi, vingt-trois [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":73,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-21747","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mobilit\u00e9<\/title>\n<meta name=\"description\" content=\"Die Schweizer Fachkompetenz in der Energietechnik - von der Erzeugung, \u00dcbertragung, Verteilung bis hin zu vielf\u00e4ltigen Anwendungsfeldern.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mobilit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Die Schweizer Fachkompetenz in der Energietechnik - von der Erzeugung, \u00dcbertragung, Verteilung bis hin zu vielf\u00e4ltigen Anwendungsfeldern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T07:45:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/05\/Demontage_1660x470.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1578\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/\",\"name\":\"Mobilit\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\"},\"datePublished\":\"2022-04-08T05:09:06+00:00\",\"dateModified\":\"2024-04-22T07:45:35+00:00\",\"description\":\"Die Schweizer Fachkompetenz in der Energietechnik - von der Erzeugung, \u00dcbertragung, Verteilung bis hin zu vielf\u00e4ltigen Anwendungsfeldern.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mobilit\u00e9","description":"Die Schweizer Fachkompetenz in der Energietechnik - von der Erzeugung, \u00dcbertragung, Verteilung bis hin zu vielf\u00e4ltigen Anwendungsfeldern.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Mobilit\u00e9","og_description":"Die Schweizer Fachkompetenz in der Energietechnik - von der Erzeugung, \u00dcbertragung, Verteilung bis hin zu vielf\u00e4ltigen Anwendungsfeldern.","og_url":"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/","og_site_name":"Electrosuisse","article_modified_time":"2024-04-22T07:45:35+00:00","og_image":[{"width":1578,"height":650,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2023\/05\/Demontage_1660x470.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/","name":"Mobilit\u00e9","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website"},"datePublished":"2022-04-08T05:09:06+00:00","dateModified":"2024-04-22T07:45:35+00:00","description":"Die Schweizer Fachkompetenz in der Energietechnik - von der Erzeugung, \u00dcbertragung, Verteilung bis hin zu vielf\u00e4ltigen Anwendungsfeldern.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/fr\/mobilite\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages\/21747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/comments?post=21747"}],"version-history":[{"count":6,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages\/21747\/revisions"}],"predecessor-version":[{"id":35100,"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages\/21747\/revisions\/35100"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/media?parent=21747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}