{"id":197,"date":"2018-06-24T11:36:30","date_gmt":"2018-06-24T09:36:30","guid":{"rendered":"https:\/\/dev-web.electrosuisse.ch\/?page_id=197"},"modified":"2022-11-28T12:03:55","modified_gmt":"2022-11-28T11:03:55","slug":"sitemap","status":"publish","type":"page","link":"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/","title":{"rendered":"Sitemap"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>Sitemap<\/h1>\n<p>[\/vc_column_text]<div class=\"wpb_sitemap_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"sitemap\"><ul id=\"menu-hauptnavigation\" class=\"sitemap__links\"><li id=\"menu-item-21727\" class=\"open-menu about-us menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-21727\"><a href=\"#\">\u00dcber uns<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-21928\" class=\"col1 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21928\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/portraet\/\">Portr\u00e4t<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-22015\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22015\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/portraet\/#report\">Dokumente<\/a><\/li>\n\t\t<li id=\"menu-item-22016\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22016\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/portraet\/#history\">Geschichte<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-21728\" class=\"col1 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21728\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/portraet\/organisation\/\">Organisation<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-22019\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22019\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/organisation\/#ft\">F\u00fchrungsteam<\/a><\/li>\n\t\t<li id=\"menu-item-22018\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22018\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/organisation\/#vorstand\">Vorstand<\/a><\/li>\n\t\t<li id=\"menu-item-22020\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22020\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/organisation\/#fvorstand\">Fachvorst\u00e4nde<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-26086\" class=\"col2 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-26086\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/karriere\/\">Karriere<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-26088\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26088\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/karriere\/du-wir\/\">Du und\u2002Wir<\/a><\/li>\n\t\t<li id=\"menu-item-26446\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-26446\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/karriere\/#berufswelten\">Berufswelten<\/a><\/li>\n\t\t<li id=\"menu-item-26594\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26594\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/karriere\/lehre-bei-electrosuisse\/\">Lehre bei Electrosuisse<\/a><\/li>\n\t\t<li id=\"menu-item-26087\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26087\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/karriere\/offene_stellen\/\">Offene Stellen<\/a><\/li>\n\t\t<li id=\"menu-item-26595\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26595\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/karriere\/kontakt\/\">Kontakt<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-21730\" class=\"col3 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21730\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/medien\/\">News Medien<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-21975\" class=\"menu-item menu-item-type-post_type menu-item-object-page current_page_parent menu-item-21975\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/medien\/news\/\">Branchennews<\/a><\/li>\n\t\t<li id=\"menu-item-227\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-227\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/medien\/publikationen\/\">Publikationen<\/a><\/li>\n\t\t<li id=\"menu-item-24032\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-24032\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/downloads\/electrosuisse\/\">Medienmitteilungen<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-21682\" class=\"open-menu subjects menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-21682\"><a href=\"#\">M\u00e4rkte<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-21684\" class=\"col1 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21684\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energieversorgung\/\">Energieversorgung<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-21997\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21997\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energie-netze\/#courses\">Veranstaltungen Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-21995\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21995\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energie-netze\/#engineering\">Engineering<\/a><\/li>\n\t\t<li id=\"menu-item-21996\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21996\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energie-netze\/#products\">Produkte<\/a><\/li>\n\t\t<li id=\"menu-item-21998\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21998\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energie-netze\/#news\">News Fachbeitr\u00e4ge<\/a><\/li>\n\t\t<li id=\"menu-item-233\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-233\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energieversorgung\/cigre-cired\/\">CIGRE\/CIRED<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-21758\" class=\"col2 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21758\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/mobilitaet\/\">Mobilit\u00e4t<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-22006\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22006\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/mobilitaet-infrastruktur\/#courses\">Veranstaltungen Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-22003\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22003\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/mobilitaet-infrastruktur\/#engineering\">Engineering<\/a><\/li>\n\t\t<li id=\"menu-item-22005\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22005\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/mobilitaet-infrastruktur\/#products\">Produkte<\/a><\/li>\n\t\t<li id=\"menu-item-22004\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22004\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/mobilitaet-infrastruktur\/#news\">News Fachbeitr\u00e4ge<\/a><\/li>\n\t\t<li id=\"menu-item-26636\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-26636\"><a target=\"_blank\" href=\"https:\/\/www.e-mobile.ch\">e-mobile<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-21704\" class=\"col3 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21704\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/produktion-und-dienstleistung\/\">Produktion und Dienstleistung<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-22007\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22007\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energieeffizienz\/#courses\">Veranstaltungen Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-22010\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22010\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energieeffizienz\/#engineering\">Engineering<\/a><\/li>\n\t\t<li id=\"menu-item-22009\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22009\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energieeffizienz\/#products\">Produkte<\/a><\/li>\n\t\t<li id=\"menu-item-22008\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22008\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/energieeffizienz\/#news\">News Fachbeitr\u00e4ge<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-21718\" class=\"col1 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21718\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/gebaeudetechnik\/\">Geb\u00e4udetechnik<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-22000\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22000\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/gebaeudetechnik\/#courses\">Veranstaltungen Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-22002\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22002\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/gebaeudetechnik\/#engineering\">Engineering<\/a><\/li>\n\t\t<li id=\"menu-item-22001\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22001\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/gebaeudetechnik\/#products\">Produkte<\/a><\/li>\n\t\t<li id=\"menu-item-21999\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21999\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/gebaeudetechnik\/#news\">News Fachbeitr\u00e4ge<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-21759\" class=\"col2 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-21759\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/elektroinstallation\/\">Elektroinstallation<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-22013\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22013\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/elektroinstallation\/#courses\">Veranstaltungen Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-22011\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22011\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/elektroinstallation\/#engineering\">Engineering<\/a><\/li>\n\t\t<li id=\"menu-item-22014\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22014\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/elektroinstallation\/#products\">Produkte<\/a><\/li>\n\t\t<li id=\"menu-item-22012\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22012\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/elektroinstallation\/#news\">News Fachbeitr\u00e4ge<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-21731\" class=\"open-menu products-services menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-21731\"><a href=\"#\">Dienstleistungen Produkte<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-22101\" class=\"col1 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-22101\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/werden-sie-mitglied\/\">Mitgliedschaft<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-222\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-222\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/werden-sie-mitglied\/persoenliche-mitgliedschaft\/\">Pers\u00f6nliche Mitgliedschaft<\/a><\/li>\n\t\t<li id=\"menu-item-223\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-223\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/werden-sie-mitglied\/branchen-mitgliedschaft\/\">Branchen-Mitgliedschaft<\/a><\/li>\n\t\t<li id=\"menu-item-35028\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-35028\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/werden-sie-mitglied\/nachwuchsfoerderung\/\">Nachwuchsf\u00f6rderung<\/a><\/li>\n\t\t<li id=\"menu-item-14092\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14092\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/werden-sie-mitglied\/firmenverzeichnis\/\">Firmenverzeichnis<\/a><\/li>\n\t\t<li id=\"menu-item-23164\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-23164\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/downloads\/mitglieder-service\/\">Dokumente<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-31092\" class=\"col1 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-31092\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/medien\/abonnemente\/\">Abonnemente<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-31093\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-31093\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/abonnemente\/#bulletin\">Fachzeitschriften<\/a><\/li>\n\t\t<li id=\"menu-item-31094\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-31094\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/abonnemente\/#nin\">NIN online<\/a><\/li>\n\t\t<li id=\"menu-item-31095\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-31095\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/abonnemente\/#toolbox\">Toolbox<\/a><\/li>\n\t\t<li id=\"menu-item-31096\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-31096\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/abonnemente\/#sng\">SNG 491000<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-22198\" class=\"col2 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-22198\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/\">Normung<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-263\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-263\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/so-funktioniert-normung\/\">Wie funktioniert Normung?<\/a><\/li>\n\t\t<li id=\"menu-item-1961\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1961\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/normdokumente\/\">Normdokumente<\/a><\/li>\n\t\t<li id=\"menu-item-16050\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16050\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/ressourcen-und-know-how\/\">Ressourcen und Know-How<\/a><\/li>\n\t\t<li id=\"menu-item-1958\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1958\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/ces\/\">CES<\/a><\/li>\n\t\t<li id=\"menu-item-1960\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1960\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/cenelec\/\">CENELEC (CEN\/CENELEC)<\/a><\/li>\n\t\t<li id=\"menu-item-1959\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1959\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/iec\/\">IEC (ISO\/IEC)<\/a><\/li>\n\t\t<li id=\"menu-item-14839\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14839\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/normungsantrag\/\">Normungsantrag<\/a><\/li>\n\t\t<li id=\"menu-item-18301\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18301\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/training\/\">Training<\/a><\/li>\n\t\t<li id=\"menu-item-18397\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18397\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/normung\/value-added-services\/\">Value Added Services<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-26945\" class=\"col3 menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-26945\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/\">Engineering<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-36054\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-36054\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/evu-support\/\">EVU-Support<\/a><\/li>\n\t\t<li id=\"menu-item-23073\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23073\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/energieversorgungssicherheit\/\">Energieversorgungssicherheit<\/a><\/li>\n\t\t<li id=\"menu-item-31015\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-31015\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/stromnetzanalyse\/\">Stromnetzanalyse<\/a><\/li>\n\t\t<li id=\"menu-item-31017\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-31017\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/dekarbonisierung\/\">Dekarbonisierung<\/a><\/li>\n\t\t<li id=\"menu-item-31314\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-31314\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/strom-und-energieeffizienz\/\">Strom- und Energieeffizienz<\/a><\/li>\n\t\t<li id=\"menu-item-25334\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25334\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/zielvereinbarung-fuer-energiegrossverbraucher\/\">Zielvereinbarung<\/a><\/li>\n\t\t<li id=\"menu-item-25335\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25335\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/power-quality\/\">Power Quality<\/a><\/li>\n\t\t<li id=\"menu-item-25336\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25336\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/nichtionisierende-strahlung\/\">Nichtionisierende Strahlung<\/a><\/li>\n\t\t<li id=\"menu-item-25337\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25337\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/energienutzungskonzept\/\">Energienutzungskonzept<\/a><\/li>\n\t\t<li id=\"menu-item-34227\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34227\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/energieoptimierung\/\">Energieoptimierung<\/a><\/li>\n\t\t<li id=\"menu-item-34228\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34228\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/energiespeicherung\/\">Energiespeicherung<\/a><\/li>\n\t\t<li id=\"menu-item-34454\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-34454\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/engineering\/energieaudit\/\">Energieaudit<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-22125\" class=\"col3 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-22125\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/inspektion-beratung\/\">Inspektion und Beratung<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-25338\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25338\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/inspektion-beratung\/blitzschutz-und-erdung\/\">Blitzschutz und Erdung<\/a><\/li>\n\t\t<li id=\"menu-item-25339\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25339\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/inspektion-beratung\/thermografie\/\">Thermografie<\/a><\/li>\n\t\t<li id=\"menu-item-25340\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25340\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/inspektion-beratung\/schaltgeraetekombinationen\/\">Schaltger\u00e4tekombinationen<\/a><\/li>\n\t\t<li id=\"menu-item-25341\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25341\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/inspektion-beratung\/sicherheitskonzepte\/\">Sicherheitskonzepte<\/a><\/li>\n\t\t<li id=\"menu-item-25361\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25361\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/inspektion-beratung\/nationalstrassen-und-eisenbahntunnels\/\">Nationalstrassen und Eisenbahntunnels<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-5142\" class=\"events open-menu menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5142\"><a href=\"#\">Veranstaltungen Kurse<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-34237\" class=\"col1 menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-34237\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/shop\/\">Kurse<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-34238\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-34238\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/?cf-lang=1\">Alle Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-21870\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21870\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/eingeschraenkte-bewilligungen\/?cf-lang=1\">Bewilligungen<\/a><\/li>\n\t\t<li id=\"menu-item-21872\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21872\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/grundlagen\/?cf-lang=1\">Grundlagen<\/a><\/li>\n\t\t<li id=\"menu-item-21873\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21873\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/installationen\/?cf-lang=1\">Installation<\/a><\/li>\n\t\t<li id=\"menu-item-37924\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-37924\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/kommunikationsnetze\/\">Kommunikationsnetze<\/a><\/li>\n\t\t<li id=\"menu-item-22274\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-22274\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/management-kurse\/\">Management-Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-21874\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21874\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/maschinen_-geraete-und-schaltgeraetekombination\/?cf-lang=1\">Maschinen, Ger\u00e4te \/ Schaltger\u00e4tekombination<\/a><\/li>\n\t\t<li id=\"menu-item-21875\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21875\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/messen\/?cf-lang=1\">Messen<\/a><\/li>\n\t\t<li id=\"menu-item-21876\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21876\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/netze\/?cf-lang=1\">Netze<\/a><\/li>\n\t\t<li id=\"menu-item-21877\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21877\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/nothilfe\/\">Nothilfe<\/a><\/li>\n\t\t<li id=\"menu-item-21878\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21878\"><a href=\"https:\/\/shop.electrosuisse.ch\/de\/weiterbildung\/kurse\/online_kurse\/\">Online-Kurse<\/a><\/li>\n\t\t<li id=\"menu-item-34703\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-34703\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/veranstaltungen\/firmenkurse\/\">Firmenkurse<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-21879\" class=\"col2 menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-21879\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/alle-tagungen\/\">Veranstaltungen<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-21880\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21880\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/alle-tagungen\/\">Alle Tagungen<\/a><\/li>\n\t\t<li id=\"menu-item-33880\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33880\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/veranstaltungen\/generalversammlung\/\">Generalversammlung<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-26747\" class=\"col3 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-26747\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/veranstaltungen\/bildungsangebot\/\">Bildungsangebot<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-34239\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-34239\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/veranstaltungen\/bildungsangebot\/\">Bildungsangebot (PDF)<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-18515\" class=\"faq menu-item menu-item-type-post_type menu-item-object-page menu-item-18515\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/faq\/\">FAQ<\/a><\/li>\n<li id=\"menu-item-14704\" class=\"shop menu-item menu-item-type-post_type menu-item-object-page menu-item-14704\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/shop\/\">Shop<\/a><\/li>\n<li id=\"menu-item-3368\" class=\"hide-desktop contact menu-item menu-item-type-post_type menu-item-object-page menu-item-3368\"><a href=\"https:\/\/dev-web.electrosuisse.ch\/de\/kontakt\/\">Kontakt<\/a><\/li>\n<li id=\"menu-item-3367\" class=\"hide-desktop myelectrosuisse menu-item menu-item-type-custom menu-item-object-custom menu-item-3367\"><a href=\"https:\/\/my.electrosuisse.ch\/de\/login.htm\">myElectrosuisse<\/a><\/li>\n<\/ul><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Sitemap [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":376,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-197","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sitemap - Electrosuisse<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sitemap - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] Sitemap [\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-28T11:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/12\/Electrosuisse_Ueber_uns_1578x650.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1578\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/\",\"name\":\"Sitemap - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/de\/#website\"},\"datePublished\":\"2018-06-24T09:36:30+00:00\",\"dateModified\":\"2022-11-28T11:03:55+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/de\/#website\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/de\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-web.electrosuisse.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/de\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/dev-web.electrosuisse.ch\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sitemap - Electrosuisse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Sitemap - Electrosuisse","og_description":"[vc_row][vc_column][vc_column_text] Sitemap [\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/","og_site_name":"Electrosuisse","article_modified_time":"2022-11-28T11:03:55+00:00","og_image":[{"width":1578,"height":650,"url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2022\/12\/Electrosuisse_Ueber_uns_1578x650.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/","url":"https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/","name":"Sitemap - Electrosuisse","isPartOf":{"@id":"https:\/\/dev-web.electrosuisse.ch\/de\/#website"},"datePublished":"2018-06-24T09:36:30+00:00","dateModified":"2022-11-28T11:03:55+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-web.electrosuisse.ch\/de\/sitemap\/"]}]},{"@type":"WebSite","@id":"https:\/\/dev-web.electrosuisse.ch\/de\/#website","url":"https:\/\/dev-web.electrosuisse.ch\/de\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/dev-web.electrosuisse.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-web.electrosuisse.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dev-web.electrosuisse.ch\/de\/#organization","name":"Electrosuisse","url":"https:\/\/dev-web.electrosuisse.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev-web.electrosuisse.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/dev-web.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/dev-web.electrosuisse.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."}]}},"_links":{"self":[{"href":"https:\/\/dev-web.electrosuisse.ch\/de\/wp-json\/wp\/v2\/pages\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-web.electrosuisse.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev-web.electrosuisse.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-web.electrosuisse.ch\/de\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":0,"href":"https:\/\/dev-web.electrosuisse.ch\/de\/wp-json\/wp\/v2\/pages\/197\/revisions"}],"wp:attachment":[{"href":"https:\/\/dev-web.electrosuisse.ch\/de\/wp-json\/wp\/v2\/media?parent=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}